{"id":2168,"date":"2019-01-16T11:24:00","date_gmt":"2019-01-16T09:24:00","guid":{"rendered":"http:\/\/labsk.net\/clubmartes\/?p=2168"},"modified":"2019-02-28T13:07:50","modified_gmt":"2019-02-28T11:07:50","slug":"cambio-en-el-tema","status":"publish","type":"post","link":"https:\/\/labsk.net\/clubmartes\/cambio-en-el-tema\/","title":{"rendered":"Cambio en el tema"},"content":{"rendered":"\n<p class=\"justify-text wp-block-paragraph\">Como habr\u00e9is comprobado llevamos unos d\u00edas con un tema nuevo en el blog. B\u00e1sicamente, me v\u00ed obligado a cambiarlo porque con las \u00faltimas actualizaciones de wordpress el tema antiguo (que ten\u00eda ya bastantes a\u00f1os) hab\u00eda quedado obsoleto (funciones <em>deprecated<\/em>) y era un coladero de spam. <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Al final opt\u00e9 por poner este bastante simpl\u00f3n por varios motivos: apenas tuve que hacer cambios (muy importante para futuros mantenimientos), no me gustan los temas excesivamente recargados, me gusta que sean simplones pero funcionales (este lo cumple), y el modo responsive (sobre todo para navegar por movil\/tablet me pareci\u00f3 una mejora sustancial respecto al anterior). Este es el resultado final. Espero que el cambio sea a mejor. Nos leemos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como habr\u00e9is comprobado llevamos unos d\u00edas con un tema nuevo en el blog. B\u00e1sicamente, me v\u00ed obligado a cambiarlo porque con las \u00faltimas actualizaciones de wordpress el tema antiguo (que ten\u00eda ya bastantes a\u00f1os) hab\u00eda quedado obsoleto (funciones deprecated) y era un coladero de spam. Al final opt\u00e9 por poner este bastante simpl\u00f3n por varios &hellip; <a href=\"https:\/\/labsk.net\/clubmartes\/cambio-en-el-tema\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Cambio en el tema<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[333,334],"class_list":["post-2168","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-anuncio","tag-tema"],"_links":{"self":[{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/posts\/2168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/comments?post=2168"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/posts\/2168\/revisions"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/media?parent=2168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/categories?post=2168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/tags?post=2168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}