{"id":246,"count":1,"description":"","link":"https:\/\/labsk.net\/clubmartes\/tag\/el-esqueleto-de-la-calle-alcala\/","name":"El esqueleto de la calle Alcal\u00e1","slug":"el-esqueleto-de-la-calle-alcala","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/tags\/246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/posts?tags=246"},{"href":"https:\/\/labsk.net\/clubmartes\/wp-json\/wp\/v2\/pages?tags=246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}