{"id":12188,"date":"2012-03-11T08:40:32","date_gmt":"2012-03-11T07:40:32","guid":{"rendered":"http:\/\/www.labsk.net\/wkr\/?p=12188"},"modified":"2012-03-10T15:05:13","modified_gmt":"2012-03-10T14:05:13","slug":"distopia-creer-en-lo-imposible-v","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/12188\/","title":{"rendered":"Distopia: Creer en lo Imposible (V)"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/i41.tinypic.com\/2e5jbxs.jpg\" alt=\"Enfermos mentales\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><strong>ENFERMOS MENTALES<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Quiz\u00e1s est\u00e1 sea el trasfondo m\u00e1s evidente y el m\u00e1s f\u00e1cil de introducir en nuestro Universo de juego. Y es sencillamente que<strong> nuestros protagonistas padecen alguna enfermedad mental<\/strong>, que sufren desde una edad temprana, y de la que han aprendido a convivir con ella de alguna manera, o al menos eso creen ellos. El hecho de que sufran experiencias extra\u00f1as a las que se enfrentan casi a diario, que les sacuden y destrozan, hace que, poco a poco, resulten mentalmente fr\u00e1giles y susceptibles a cualquier perturbaci\u00f3n emocional.<strong> Una enfermedad que les hace vivir una fantas\u00eda continua que no tiene por qu\u00e9 ce\u00f1irse a la realidad.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>La mayor\u00eda de los triplehexas son <a href=\"http:\/\/es.wikipedia.org\/wiki\/Psicosis\" target=\"_blank\">psic\u00f3ticos<\/a><\/strong>, y cuando se ven inmersos en alguna situaci\u00f3n tensa o se ven conmocionados, cambian. Muchos se sienten perseguidos o sufren episodios paranoides. Eso implica que tienen verdaderas limitaciones en su vida cotidiana. Lo m\u00e1s cercano e inmediato, es que les resulta problem\u00e1tico mantener relaciones emocionales con otra gente, y la rompen en el momento que haga demasiado \u00edntima.<\/p>\n<p style=\"text-align: justify;\">Todo esto podr\u00eda ser una extraordinaria respuesta al motivo de porqu\u00e9 que muchos de los triplehexas poseen fobias internas, y sufren de alucinaciones e ilusiones, tics o temblores incontrolados, psicosis reactiva y rituales compulsivos, y finalmente esquizofrenia.<\/p>\n<p style=\"text-align: justify;\"><strong>Una de las enfermedades m\u00e1s frecuentes en todos ellos, adem\u00e1s de la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Hexakosioihexekontahexafobia\" target=\"_blank\">hexakosioihexekontahexafobia <\/a>(miedo irracional al n\u00famero 666) es la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Apofenia\" target=\"_blank\">apofenia<\/a><\/strong>, consistente en la experiencia de ver patrones, conexiones o ambos en sucesos aleatorios o datos sin sentido. El t\u00e9rmino fue acu\u00f1ado en 1959 por Klaus Conrad, quien lo defini\u00f3 como \u00abvisi\u00f3n sin motivos de conexiones\u00bb acompa\u00f1ada de \u00abexperiencias concretas de dar sentido anormalmente a lo que no lo tiene\u00bb.<\/p>\n<p style=\"text-align: justify;\">Todas las personas tenemos, en mayor o menor medida, una cierta tendencia a buscar (y encontrar) patrones y relaciones causa-efecto en una gran variedad de situaciones. Es una capacidad que seguramente ha tenido valor adaptativo, pues ha permitido atribuir orden y l\u00f3gica a buen n\u00famero de eventos naturales propios del medio en que viv\u00edan nuestros antepasados. Y por lo mismo, ha permitido prever acontecimientos que, por su naturaleza, han podido resultar claves para sobrevivir o progresar.\u00a0Pero la apofenia es otra cosa, porque <strong>se produce cuando se extrema esa tendencia a detectar patrones, de manera que se percibe lo que no existe, ya se trate de relaciones causales, ya de figuras u otro tipo de percepciones<\/strong>. Si no sabes a que me refiero, Jim Carrey lo interpreta bastante bien en la pel\u00edcula \u201cEl N\u00famero 23\u201d, cuando se obsesiona precisamente con el n\u00famero 23.<\/p>\n<p style=\"text-align: justify;\">Conrad describi\u00f3 originalmente este fen\u00f3meno en relaci\u00f3n con la <strong>distorsi\u00f3n de la realidad presente en la psicosis<\/strong>, pero se ha llegado a ser m\u00e1s ampliamente usado para describir esta tendencia en individuos sanos sin que esto implique necesariamente la presencia de enfermedades neurol\u00f3gicas o mentales.<\/p>\n<p style=\"text-align: justify;\">Se trata pues, de un fen\u00f3meno psicol\u00f3gico lim\u00edtrofe entre la psicosis y la creatividad, que consiste en la uni\u00f3n cerebral de dos elementos sin un aparente patr\u00f3n com\u00fan.<\/p>\n<p style=\"text-align: justify;\">Parece ser, y as\u00ed lo constatan diversos cient\u00edficos, que\u00a0<strong>la apofenia es consecuencia de una actividad excesivamente alta del sistema dopamin\u00e9rgico<\/strong>, sistema formado por los circuitos o conexiones neuronales en los que la dopamina es el neurotransmisor que conecta a unas neuronas con otras. Brugger ha observado que una alta actividad relacionada con la dopamina provoca la percepci\u00f3n de patrones y significados en una medida superior a la normal. Y cuando la actividad dopamin\u00e9rgica es normal o baja no ocurre tal cosa. Y tambi\u00e9n se sabe que la tendencia a detectar fen\u00f3menos o im\u00e1genes inexistentes se ve fuertemente acentuada por efecto de determinadas patolog\u00edas, como la esquizofrenia o del consumo de f\u00e1rmacos, como las anfetaminas.<\/p>\n<p style=\"text-align: justify;\">El caso m\u00e1s genuino de apofenia es el que consiste en la percepci\u00f3n de figuras o palabras en una pantalla de televisi\u00f3n en la que solo hay rayas que se mueven, aparecen y desaparecen al azar. Hay personas que ven algo concreto, definido y otras no lo ven. Entonces entra en escena\u00a0la<strong> <a href=\"http:\/\/es.wikipedia.org\/wiki\/Pareidolia\" target=\"_blank\">pareidolia<\/a><\/strong>, un fen\u00f3meno psicol\u00f3gico consistente en que un est\u00edmulo vago y aleatorio (habitualmente una imagen) es percibido err\u00f3neamente como una forma reconocible. Es el que mejor designa las alteraciones perceptivas en las que, a partir de un campo real de percepci\u00f3n escasamente estructurado, el individuo cree percibir algo distinto, <strong>mezclando lo percibido con lo fantaseado<\/strong>. En este sentido es una forma de ilusi\u00f3n o percepci\u00f3n enga\u00f1osa que se diferencia claramente de las alucinaciones, seudoalucinaciones, alucinosis o metamorfopcias. La tendencia a atribuir a ciertas sucesiones de eventos la categor\u00eda de conspiraciones ser\u00eda tambi\u00e9n una variedad de apofenia. En este caso ser\u00eda una apofenia relativa a una serie de relaciones causa-efecto en un contexto conspirativo de car\u00e1cter eminentemente pol\u00edtico.<\/p>\n<p style=\"text-align: justify;\">Otro frecuente en algunos triplehexas es el <strong><a href=\"http:\/\/es.wikipedia.org\/wiki\/S%C3%ADndrome_de_Asperger\" target=\"_blank\">s\u00edndrome de Asperger<\/a><\/strong>,\u00a0un conjunto de condiciones mentales y conductuales que forma parte del espectro de trastornos aut\u00edsticos. El sujeto afectado muestra dificultades en la interacci\u00f3n social y en la comunicaci\u00f3n de severidad variable, as\u00ed como actividades e intereses en \u00e1reas que suelen ser muy restringidas y en muchos casos estereot\u00edpicas. Se diferencia del trastorno autista en que en el trastorno de Asperger no se observa retraso en el desarrollo del lenguaje, no existiendo una perturbaci\u00f3n cl\u00ednicamente significativa en su adquisici\u00f3n. \u00a0Sin embargo, debido a que la inteligencia de la mayor\u00eda de las personas con Asperger es normal, el resto de las personas, en general, no los percibe como autistas sino como personas con un comportamiento muy peculiar o extra\u00f1o. Remarcablemente, <strong>el s\u00edndrome de Asperger en ocasiones se da en concomitancia con una inteligencia superior a la normal o con un talento superior en una o m\u00faltiples \u00e1reas espec\u00edficas<\/strong>, a modo de <strong><a href=\"http:\/\/es.wikipedia.org\/wiki\/Savantismo\" target=\"_blank\">savantismo<\/a><\/strong> (s\u00edndrome del sabio), por ejemplo, Leonardo Da Vinci, por ejemplo, -Asperger especulado- presentaba m\u00faltiples caracter\u00edsticas de este tipo de comportamiento.<\/p>\n<p style=\"text-align: justify;\">Y en definitiva, basta con observar el <strong><a href=\"http:\/\/es.wikipedia.org\/wiki\/Manual_Estad%C3%ADstico_de_Diagn%C3%B3stico_de_Trastornos_Mentales\" target=\"_blank\">Manual diagn\u00f3stico y estad\u00edstico de los trastornos mentales<\/a><\/strong> y buscar aquellos que puedan servirnos para dar una explicaci\u00f3n a la peculiaridad de nuestros protagonistas. Cualquier cosa que a\u00a0nosotros nos sirva como explicaci\u00f3n para nuestro Universo de juego.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ENFERMOS MENTALES Quiz\u00e1s est\u00e1 sea el trasfondo m\u00e1s evidente y el m\u00e1s f\u00e1cil de introducir en nuestro Universo de juego. Y es sencillamente que nuestros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[1267,55],"class_list":["post-12188","post","type-post","status-publish","format-standard","hentry","category-juegos-de-rol","category-proyectos","tag-creer-en-lo-imposible","tag-distopia"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/12188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=12188"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/12188\/revisions"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=12188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=12188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=12188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}