{"id":14651,"date":"2013-04-19T10:02:33","date_gmt":"2013-04-19T08:02:33","guid":{"rendered":"http:\/\/www.labsk.net\/wkr\/?p=14651"},"modified":"2022-01-09T16:30:01","modified_gmt":"2022-01-09T15:30:01","slug":"ki-ken-tai-no-ichi","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/14651\/","title":{"rendered":"KI-KEN-TAI no ichi"},"content":{"rendered":"\n<p class=\"justify-text wp-block-paragraph\"><a href=\"https:\/\/www.box.com\/s\/qewyc71drcanulkct6y6\" target=\"_blank\" rel=\"noopener\"><strong>KI-KEN-TAI no ichi<\/strong><\/a> no es otra cosa que un Gin Rummy tematizado. Para aquellos no conozc\u00e1is que es el Gin Rummy es un sencillo y popular juego de naipes para dos jugadores, de origen espa\u00f1ol, creado por Elwood T. Baker en 1909. El Gin fue creado con la intenci\u00f3n de ser m\u00e1s r\u00e1pido que el est\u00e1ndar rummy, pero no tan espont\u00e1neo como el Knock Rummy. \u00daltimamente ha llegado a ser uno de los juegos favoritos en los Estados Unidos, por sus simples y variadas combinaciones, que permiten que pueda jugarse con suma rapidez.<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">KI-KEN-TAI no ichi es un juego ideal para dos jugadores, aunque se puede jugar tambi\u00e9n entre tres (con variante) o cuatro personas (con variante y dos barajas). Su duraci\u00f3n es de 20-30 minutos a lo sumo.<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">El nombre de KI-KEN-TAI no ichi viene de uno de los principios del Kendo que significa que el esp\u00edritu, (Ki) la espada (Ken) y el cuerpo (Tai) tienen que actuar a la vez, el KI se demuestra gritando, el KIAI, la zona de ataque simult\u00e1neamente al golpe, demostrando la total implicaci\u00f3n, f\u00edsica y mental, en el ataque.<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Consiste en formar, cada jugador en su mano, combinaciones de cuatro o m\u00e1s cartas, para sobrepasar antes que el jugador contrario, en varios juegos parciales, los 100 puntos que se requieren para ganar la partida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para jugar a KI-KEN-TAI no ichi usaremos <a href=\"http:\/\/www.labsk.net\/index.php?topic=59232.0\" target=\"_blank\" rel=\"noopener\">algunas cartas del Seven Card Samurai<\/a> redise\u00f1adas por feylong.<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\"><span style=\"color: #ff0000;\"><strong>Advertencia.<\/strong><\/span>&nbsp;Estas reglas que comparto son la&nbsp;<em>versi\u00f3n&nbsp;1.0alpha<\/em>&nbsp;y no son las definitivas; son las que utilizar\u00e9 para la prueba del juego. Simplemente las hago p\u00fablicas por si alguien m\u00e1s quiere probar el juego y dar su opini\u00f3n. Si doy el visto bueno ya actualizar\u00e9 esta misma entrada con las reglas definitivas. \u00a1A disfrutarlo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KI-KEN-TAI no ichi no es otra cosa que un Gin Rummy tematizado. Para aquellos no conozc\u00e1is que es el Gin Rummy es un sencillo y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[1690,48,915,517,1691],"class_list":["post-14651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos-de-mesa","tag-ki-ken-tai-no-ichi","tag-print-and-play","tag-reciclaje-ludico","tag-rummy","tag-seven-card-samurai"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/14651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=14651"}],"version-history":[{"count":2,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/14651\/revisions"}],"predecessor-version":[{"id":20679,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/14651\/revisions\/20679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/20677"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=14651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=14651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=14651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}