{"id":15205,"date":"2013-10-31T15:57:49","date_gmt":"2013-10-31T13:57:49","guid":{"rendered":"http:\/\/labsk.net\/wkr\/?p=15205"},"modified":"2015-06-04T15:13:47","modified_gmt":"2015-06-04T13:13:47","slug":"ugo","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/15205\/","title":{"rendered":"UGO!"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/boardgamegeek.com\/boardgame\/139326\/ugo\" target=\"_blank\">UGO!<\/a>\u00a0<\/strong>es un juego de cartas, dise\u00f1ado por\u00a0Ronald Hoekstra,\u00a0Thomas Jansen y\u00a0Patrick Zuidhof,\u00a0en el que\u00a0los jugadores tratan de fundar un poderoso reino expandiendo su imperio mediante la anexi\u00f3n de pa\u00edses y asegur\u00e1ndose de mantener sus tierras cultivadas para garantizar su prosperidad.<\/p>\n<p style=\"text-align: justify;\">Se trata de un\u00a0sencillo juego de bazas. El jugador inicial comienza jugando una carta de su mano y el resto de jugadores en el sentido de las agujas del reloj intentan seguirle jugando cartas del mismo color en el caso de que sea posible o bien de otros colores. El jugador que juegue la carta m\u00e1s alta gana la mano y en caso de empate, el jugador cuya carta fuese del mismo color que la del jugador inicial es el ganador de la ronda. Si ninguno de los jugadores juega cartas del mismo color que el jugador inicial \u00e9ste es el ganador.<\/p>\n<p style=\"text-align: justify;\">El ganador coloca las cartas en sus cartas de reino de izquierda a derecha ordenadas por color. Si el jugador no tiene nada en las cartas de reino puede ordenarlas a su elecci\u00f3n. Sin embargo, si ya ten\u00eda cartas sobre las cartas de reino ha de colocarlas sobre ellas haciendo coincidir su color. Al comenzar una nueva ronda los jugadores ya no podr\u00e1n cambiar las cartas de posici\u00f3n.\u00a0El vencedor de la ronda de juego ser\u00e1 adem\u00e1s el jugador que comienza de la siguiente.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/boardgamegeek.com\/boardgame\/139326\/ugo\" target=\"_blank\"><strong>UGO!<\/strong><\/a>\u00a0ha sido publicado por la editorial\u00a0Playthisone\u00a0en una edici\u00f3n multiling\u00fce que contiene las <a href=\"http:\/\/www.playthisone.com\/en\/downloads-en\/manuals\" target=\"_blank\">reglas<\/a> en holand\u00e9s, ingl\u00e9s, franc\u00e9s y alem\u00e1n. Pero lo mejor es que si posees <a href=\"http:\/\/labsk.net\/wkr\/archives\/224\/\" target=\"_blank\">un mazo de\u00a0Sticheln o de Rage,<\/a> su <a href=\"http:\/\/labsk.net\/wkr\/archives\/tag\/reciclaje-ludico\/\" target=\"_blank\">reciclaje l\u00fadico<\/a> es inmediato (ya que solo usa 5 palos con cartas del 0 al 8).<\/p>\n<p style=\"text-align: justify;\"><strong>Ficha en BGG:<\/strong><br \/>\n<a href=\"http:\/\/boardgamegeek.com\/boardgame\/139326\/ugo\">http:\/\/boardgamegeek.com\/boardgame\/139326\/ugo<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Reglamento:<\/strong><br \/>\n<a href=\"http:\/\/www.playthisone.com\/en\/downloads-en\/manuals\" target=\"_blank\">http:\/\/www.playthisone.com\/en\/downloads-en\/manuals<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UGO!\u00a0es un juego de cartas, dise\u00f1ado por\u00a0Ronald Hoekstra,\u00a0Thomas Jansen y\u00a0Patrick Zuidhof,\u00a0en el que\u00a0los jugadores tratan de fundar un poderoso reino expandiendo su imperio mediante la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[915,1774],"class_list":["post-15205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos-de-mesa","tag-reciclaje-ludico","tag-ugo"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/15205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=15205"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/15205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/17610"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=15205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=15205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=15205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}