{"id":15333,"date":"2013-12-14T10:47:00","date_gmt":"2013-12-14T08:47:00","guid":{"rendered":"http:\/\/labsk.net\/wkr\/?p=15333"},"modified":"2015-12-30T21:03:35","modified_gmt":"2015-12-30T19:03:35","slug":"un-imperio-en-8-minutos-taj-mahal","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/15333\/","title":{"rendered":"Un imperio en 8 minutos (Taj Mahal)"},"content":{"rendered":"<p style=\"text-align: justify;\">Ayer estuve por mi tienda habitual y acab\u00e9 compr\u00e1ndome el juego <a href=\"http:\/\/boardgamegeek.com\/boardgame\/131366\/eight-minute-empire\" target=\"_blank\">\u00abUn imperio en 8 minutos\u00bb<\/a> de Ryan Laukat, y que acaba de publicar Devir en espa\u00f1ol. Va a ser el acompa\u00f1amiento ideal para las <a title=\"Juegos para 2 jugadores en un bar\" href=\"http:\/\/labsk.net\/wkr\/archives\/5868\/\" target=\"_blank\">partidas en el bar<\/a>.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a1Crea un imperio y conquista el mundo en menos de 10 minutos!\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><em>En\u00a0Un imperio en 8 minutos\u00a0los jugadores deben elegir en su turno una carta de entre seis disponibles. La carta proporciona una mercanc\u00eda y tambi\u00e9n una acci\u00f3n que el jugador deber\u00e1 realizar de inmediato. Las acciones permiten ir conquistando el mapa poco a poco, pero las mercanc\u00edas aportan puntos al final de la partida, de modo que los jugadores no podr\u00e1n descuidar ninguno de los dos aspectos.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Un imperio en 8 minutos\u00a0es un juego de control de zonas extremadamente r\u00e1pido pero repleto de decisiones dif\u00edciles. Es muy f\u00e1cil de aprender y perfecto para cuando s\u00f3lo dispones de unos pocos minutos.<\/em><\/p>\n<p style=\"text-align: justify;\">Su PVP 15 euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer estuve por mi tienda habitual y acab\u00e9 compr\u00e1ndome el juego \u00abUn imperio en 8 minutos\u00bb de Ryan Laukat, y que acaba de publicar Devir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[6],"tags":[20,1797],"class_list":["post-15333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-ludoteca","tag-ludoteca","tag-un-imperio-en-8-minutos"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/15333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=15333"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/15333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/19018"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=15333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=15333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=15333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}