{"id":15346,"date":"2013-12-19T11:21:48","date_gmt":"2013-12-19T09:21:48","guid":{"rendered":"http:\/\/labsk.net\/wkr\/?p=15346"},"modified":"2023-07-06T13:57:07","modified_gmt":"2023-07-06T12:57:07","slug":"una-civilizacion-en-45-minutos","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/15346\/","title":{"rendered":"Una civilizaci\u00f3n en 45 minutos"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Convi\u00e9rtete en el Amo del Mundo estableciendo y liderando una civilizaci\u00f3n desde los albores del hombre hasta la era espacial. Descubre nuevos avances tecnol\u00f3gicos claves para el desarrollo de la humanidad y construye el imperio m\u00e1s poderoso que el mundo haya conocido.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Una civilizaci\u00f3n en 45 minutos<\/strong> es mi pr\u00f3ximo proyecto de juego, en el que llevo trabajando esta semana. Ya tengo dise\u00f1ado el primer prototipo para las pruebas de juego y un primer boceto del reglamento (de 4 p\u00e1ginas). El nombre es un gui\u00f1o al juego <a title=\"Un imperio en 8 minutos (Taj Mahal)\" href=\"http:\/\/labsk.net\/wkr\/archives\/15333\/\" target=\"_blank\" rel=\"noopener\">Un imperio en 8 minutos<\/a> de\u00a0Ryan Laukat. Mi intenci\u00f3n es dise\u00f1ar un juego para <strong>1-2 jugadores<\/strong> que se pueda jugar en <strong>45 minutos<\/strong> que represente, de una manera abstracta y simple, el desarrollo de la humanidad, de sus urbes y sus tecnolog\u00edas.<\/p>\n<p style=\"text-align: justify;\">Para aumentar la civilizaci\u00f3n disponemos de unas cartas de Exploraci\u00f3n con la que vamos explorando y ampliando nuestros dominios con nuevos terrenos, que a su vez que nos proporcionan m\u00e1s recursos.\u00a0Hay 6 tipos de recursos que se pueden obtener y gastar durante la partida: Comida, Madera, Mineral, Dinero, Poblaci\u00f3n y Progreso. El Dinero es un comod\u00edn que se puede usar como cualquiera de los otros cinco.\u00a0Solo se usa un \u00fanico tipo de marcador (cubito) para representar todos los tipos de recursos que hay en el juego. Se sabr\u00e1 a qu\u00e9 tipo corresponde dependiendo de en el lugar del tablero personal (que se va construyendo a la largo de la partida) donde se encuentren.<\/p>\n<p style=\"text-align: justify;\">Los\u00a0<strong>componentes del juego<\/strong>\u00a0son <del>108<\/del>\u00a0114 cartas (que ya tengo dise\u00f1adas a lo\u00a0<em>wkr-style<\/em>), un buen pu\u00f1ado de marcadores (recomiendo cubitos) y 2d10 (que se usan para marcar el n\u00famero de Desarrollos conseguidos a lo largo de la partida).<\/p>\n<p style=\"text-align: justify;\">El<strong> Mazo de Eras <\/strong>est\u00e1 dividido en 4 bloques: Antig\u00fcedad, Edad Media y Renacimiento, Edad moderna y Edad contempor\u00e1nea.\u00a0En cada Era hay <strong>solo<\/strong> 9 avances tecnol\u00f3gicos y un pu\u00f1ado de cartas de Acci\u00f3n con el que podremos ir realizando cosas.<\/p>\n<p style=\"text-align: justify;\">Los<strong>\u00a0Avances Tecnol\u00f3gicos<\/strong>\u00a0sirven para ir progresando como civilizaci\u00f3n. Hay algunos Avances Tecnol\u00f3gicos, que son m\u00e1s importantes y claves, y proporcionan habilidades especiales durante la partida a quien(es) los consiguen.<\/p>\n<p style=\"text-align: justify;\">Hay 4 tipos de <strong>Cartas de Acci\u00f3n<\/strong>: Explorar, Recolectar (Comida, Madera, Mineral o especial), Investigar (Dinero por Progreso), y Manufacturar (2 Mineral x 1 Dinero).<\/p>\n<p style=\"text-align: justify;\">Hay 4 <strong>Cat\u00e1strofes<\/strong> (1 por Era): Erupci\u00f3n Volc\u00e1nica, Epidemia de Peste, Guerra Mundial y Neoliberalismo. Cuando aparecen se resuelven de inmediato. Son trabas.<\/p>\n<p style=\"text-align: justify;\">Hay 4 <strong>L\u00edderes<\/strong> (1 por Era): S\u00f3crates, Leonardo da Vinci, Tom\u00e1s Alba Edison y <del>Alexander Fleming<\/del>\u00a0Albert Einstein. Son p\u00fablicos desde el principio de la partida y quien cumple sus requisitos los obtiene. Proporcionan una habilidad especial cuando se descartan (sin usar una acci\u00f3n). Son ayudas.<\/p>\n<p style=\"text-align: justify;\">Cada jugador en su turno podr\u00e1 realizar\u00a0<strong>dos<\/strong>\u00a0acciones entre cinco opciones a elegir: Activar una carta, Intercambiar un Avance Tecnol\u00f3gico, Comerciar (3&#215;1), Aumentar Poblaci\u00f3n o Pasar.<\/p>\n<p style=\"text-align: justify;\">El <strong>objetivo del juego<\/strong> es simple: ser el primer jugador en conseguir y activar la tecnolog\u00eda avanzada (n\u00ba 36) del Proyecto Manhattan; para ello necesitar\u00e1 haber conseguido durante la partida 10 Desarrollos (que se van marcando con el d10) y tener 8 de Progreso. Si nadie lo logra,\u00a0bastar\u00e1 con ser el jugador m\u00e1s desarrollado al final de la partida.<\/p>\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.5em;\">Un juego para los fans del <\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/es.wikipedia.org\/wiki\/Civilization_(serie)\" target=\"_blank\" rel=\"noopener\">Sid Meier&#8217;s Civilizaci\u00f3n<\/a><span style=\"line-height: 1.5em;\"> (la saga de videojuegos), <\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/boardgamegeek.com\/boardgame\/71\/civilization\" target=\"_blank\" rel=\"noopener\">Civilization<\/a><span style=\"line-height: 1.5em;\"> y <\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/boardgamegeek.com\/boardgameexpansion\/177\/advanced-civilization\" target=\"_blank\" rel=\"noopener\">Advanced Civilization<\/a><span style=\"line-height: 1.5em;\">, <\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/boardgamegeek.com\/boardgame\/3633\/sid-meiers-civilization-the-boardgame\" target=\"_blank\" rel=\"noopener\">Sid Meier&#8217;s Civilization: The Boardgame<\/a><span style=\"line-height: 1.5em;\">,\u00a0<\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/boardgamegeek.com\/boardgame\/77130\/sid-meiers-civilization-the-board-game\">Sid Meier&#8217;s Civilization: The Board Game<\/a><span style=\"line-height: 1.5em;\">\u00a0(2010),\u00a0<\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/boardgamegeek.com\/boardgame\/28044\/pocket-civ\" target=\"_blank\" rel=\"noopener\">Pocket Civ<\/a><span style=\"line-height: 1.5em;\">, <\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/boardgamegeek.com\/boardgame\/90041\/principato\" target=\"_blank\" rel=\"noopener\">Principato<\/a><span style=\"line-height: 1.5em;\">, <\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/boardgamegeek.com\/boardgame\/34707\/the-hanging-gardens\" target=\"_blank\" rel=\"noopener\">The Hanging Gardens<\/a><span style=\"line-height: 1.5em;\"> o <\/span><a style=\"line-height: 1.5em;\" href=\"http:\/\/boardgamegeek.com\/boardgame\/68448\/7-wonders\" target=\"_blank\" rel=\"noopener\">7 Wonders<\/a><span style=\"line-height: 1.5em;\">.<\/span><\/p>\n<p style=\"text-align: justify;\">Puedes seguir los progresos del juego con el tag de twitter <a href=\"https:\/\/twitter.com\/search?q=%23UnaCivilizaci%C3%B3nEn45Minutos&amp;src=hash\" target=\"_blank\" rel=\"noopener\">#UnaCivilizaci\u00f3nEn45Minutos<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Hilo en la bsk donde voy respondiendo dudas:<\/strong><br \/>\n<a href=\"http:\/\/labsk.net\/index.php?topic=124635.0\" target=\"_blank\" rel=\"noopener\">http:\/\/labsk.net\/index.php?topic=124635.0<\/a><\/p>\n<p><strong>Desc\u00e1rgalo gratis (v1.3beta):<br \/>\n<\/strong><a href=\"https:\/\/archive.org\/details\/UnaCivilizacionEn45Minutos\" target=\"_blank\" rel=\"noopener\">https:\/\/archive.org\/details\/UnaCivilizacionEn45Minutos<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\">Solo pido a cambio que si lo pruebas dejes un comentario con la experiencia y me proporciones feedback, con pros, contras y posibles mejoras. Muchas gracias.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ff0000;\">\u00a1\u00a1\u00a1Si tienes una versi\u00f3n previa, acu\u00e9rdate de descargarte la actualizaci\u00f3n de reglas y la 1era expansi\u00f3n!!!<\/span> <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Reglamento v1.3beta:<\/strong><br \/>\n<a href=\"http:\/\/labsk.net\/uc45reglas\" target=\"_blank\" rel=\"noopener\">http:\/\/labsk.net\/uc45reglas<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Proyecto Apolo (1era. Expansi\u00f3n):<\/strong><br \/>\n<a href=\"http:\/\/labsk.net\/wkr\/archives\/15705\/\" target=\"_blank\" rel=\"noopener\">http:\/\/labsk.net\/wkr\/archives\/15705\/<\/a><\/p>\n<p><strong>Traducci\u00f3n al ingl\u00e9s (gracias a RaDiKal):<\/strong><br \/>\n<a href=\"https:\/\/boardgamegeek.com\/filepage\/239665\/45-min-civ-rules-english\" target=\"_blank\" rel=\"noopener\">https:\/\/boardgamegeek.com\/filepage\/239665\/45-min-civ-rules-english<\/a><br \/>\n(reglamento, variantes, expansiones y faq)<\/p>\n<p style=\"text-align: justify;\">El juego tiene una <a href=\"http:\/\/creativecommons.org\/licenses\/by-nc-sa\/3.0\/es\/\" target=\"_blank\" rel=\"noopener\">licencia CC by-nc-sa<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convi\u00e9rtete en el Amo del Mundo estableciendo y liderando una civilizaci\u00f3n desde los albores del hombre hasta la era espacial. Descubre nuevos avances tecnol\u00f3gicos claves [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3,8],"tags":[48,1982,1798],"class_list":["post-15346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos-de-mesa","category-proyectos","tag-print-and-play","tag-prototipo","tag-una-civilizacion-en-45-minutos"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/15346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=15346"}],"version-history":[{"count":4,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/15346\/revisions"}],"predecessor-version":[{"id":21288,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/15346\/revisions\/21288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/16731"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=15346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=15346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=15346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}