{"id":16022,"date":"2014-10-21T10:50:22","date_gmt":"2014-10-21T08:50:22","guid":{"rendered":"http:\/\/labsk.net\/wkr\/?p=16022"},"modified":"2016-03-30T13:49:08","modified_gmt":"2016-03-30T12:49:08","slug":"quest-providence-urbania-mondo-sapiens-grimoire-dracotienda","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/16022\/","title":{"rendered":"Quest: A Time of Heroes + Province + Urbania + Mondo Sapiens + Grimoire (Dracotienda)"},"content":{"rendered":"<p style=\"text-align: justify;\">Pedido realizado esta misma ma\u00f1ana a <a href=\"http:\/\/www.dracotienda.com\">Dracotienda<\/a>\u00a0aprovechando algunas de sus ofertas (por lo visto por su d\u00e9cimo aniversario) para aumentar mi ludoteca. Necesitaba aire fresco tras una crisis l\u00fadica de identidad. Mis opiniones en rojo.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/boardgamegeek.com\/boardgame\/81542\/quest-time-heroes\" target=\"_blank\">Quest:\u00a0A Time of Heroes<\/a>\u00a0(Attack of the Orcs) = 9.95EUR<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/boardgamegeek.com\/boardgame\/154259\/province\" target=\"_blank\">Province<\/a> = 8.95EUR<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/boardgamegeek.com\/boardgame\/93541\/urbania\" target=\"_blank\">Urbania<\/a> + Expansiones Mayfair = 14.95EUR<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/boardgamegeek.com\/boardgame\/118293\/mondo-sapiens\" target=\"_blank\">Mondo Sapiens<\/a> \u00a0= 12.99EUR<\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/boardgamegeek.com\/boardgame\/73863\/grimoire\" target=\"_blank\">Grimoire<\/a> = 14.95EUR<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"http:\/\/cf.geekdo-images.com\/images\/pic1040805_md.jpg\" alt=\"Grimoire\" width=\"600\" \/><\/p>\n<p style=\"text-align: justify;\">El <a href=\"http:\/\/boardgamegeek.com\/boardgame\/73863\/grimoire\" target=\"_blank\">Grimoire<\/a> lo prob\u00e9 este verano, me result\u00f3 bastante simp\u00e1tico y una peque\u00f1a joya. De hecho fue de lo mejorcito que prob\u00e9 en mis vacaciones estivales (junto con el <a title=\"Pixel Tactics 2 y 3 (Level 99 Games)\" href=\"http:\/\/labsk.net\/wkr\/archives\/15940\/\" target=\"_blank\">Pixel Tactics<\/a>), as\u00ed que aprovechando su precio, cay\u00f3 en la saca. Mis agradecimientos a @darkfonix por d\u00e1rmelo a conocer. <span style=\"color: red;\">Sigo pensando que es una verdadera joya. Mucho bluff y mucha mala enjundia. Lo probe a tres jugadores y funciona mejor de lo que esperaba. Muy divertido y con una duraci\u00f3n comedida. Las ilustraciones, por cierto, me encantan. Esta edici\u00f3n de ZMan (la de la foto) adem\u00e1s es de 2-5 jugadores.<\/span><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/cf.geekdo-images.com\/images\/pic2238433_md.jpg\" alt=\"Province\" width=\"600\" \/><\/p>\n<p style=\"text-align: justify;\">El <a href=\"http:\/\/puntodevictoria.wordpress.com\/2014\/09\/17\/province-un-pequeno-gran-juego\/\" target=\"_blank\">Province<\/a> lo inclu\u00ed en mi wishlist tras leer una <a href=\"http:\/\/puntodevictoria.wordpress.com\/2014\/09\/17\/province-un-pequeno-gran-juego\/\" target=\"_blank\">rese\u00f1a en Punto de Victoria<\/a>, y como me encantan los juegos minimalistas, pues otro para la saca. Adem\u00e1s tengo ganas de hincarle el diente a la <a href=\"http:\/\/boardgamegeek.com\/filepage\/107095\/my-little-province-solo-variant\" target=\"_blank\">expansi\u00f3n en solitario que se curr\u00f3 @cruciforme<\/a>.\u00a0<span style=\"color: red;\">Despu\u00e9s de jugar varias partidas, la mayor decepci\u00f3n en lo que llevo de a\u00f1o. No se si jugamos o mal o aplicamos alguna regla mal, pero es que lo encontramos un absurdo. No veo raz\u00f3n alguna (salvo muy contadas excepciones) para no mover cada turno siempre todos los tokens. El poder de decisi\u00f3n es casi cero.<\/span><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/cf.geekdo-images.com\/images\/pic1228846_md.jpg\" alt=\"Mondo Sapiens\" width=\"600\" \/><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/boardgamegeek.com\/boardgame\/118293\/mondo-sapiens\" target=\"_blank\">Mondo Sapiens<\/a>\u00a0es uno que ten\u00eda pendiente desde hace bastante tiempo, quer\u00eda uno de puzzles y este es decentillo (y si no me equivoco tiene algo m\u00e1s de dificultad que el Mondo a secas).\u00a0<span style=\"color: red;\">Lo estren\u00e9 y no tuvo muy buena acogida en mi grupo. Algo lioso.<\/span><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/cf.geekdo-images.com\/images\/pic1519418_md.jpg\" alt=\"Urbania\" width=\"600\" \/><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/boardgamegeek.com\/boardgame\/93541\/urbania\" target=\"_blank\">Urbania<\/a>\u00a0lo ten\u00eda en el punto de mira desde que estuvo nominado como mejor juego de mesa en los\u00a0<a href=\"http:\/\/boardgamegeek.com\/boardgamehonor\/22668\/2013-uk-games-expo-best-boardgame-nominee\">2013 UK Games Expo<\/a>, si no me lo compr\u00e9 antes fue por su precio (pero estando a 15EUR lo consider\u00e9 casi un pecado no comprarlo).\u00a0<span style=\"color: red;\">Si te gustan juegos como Aventureros al tren o Africana, este juego tambi\u00e9n te gustar\u00e1. Una agradable sorpresa y justo lo que buscaba: un juego familiar de gesti\u00f3n de cartas. Tal vez los Especialistas acaban dando demasiados puntos y m\u00e1s teniendo en cuenta luego los proyectos finales. Hay que jugarlo m\u00e1s; de momento escala bien a 2 y 3 jugadores.<\/span><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/cf.geekdo-images.com\/images\/pic891612_md.jpg\" alt=\"Quest: A Time of Heroes \" width=\"600\" \/><\/p>\n<p style=\"text-align: justify;\">El\u00a0<a href=\"http:\/\/boardgamegeek.com\/boardgame\/81542\/quest-time-heroes\" target=\"_blank\">Quest. Attack of the Orcs<\/a>\u00a0fue el a\u00f1adido para llegar a los gastos de env\u00edo gratis (estaba entre este o comprarme una expansi\u00f3n del Smash Up!). A ver si tiene algo este\u00a0jueguecito de aventuras que me guste (o sino, ya pensar\u00e9 en reglas caseras).<span style=\"color: red;\">Sin haber jugado todav\u00eda, se ve claramente que la rejugabilidad es uno de sus puntos flojos, el otro es el azar en 1d10 en las tiradas. No obstante, el material que lleva, es la ca\u00f1a. No te digo que me curre algo con las barajas y recicle las minis para el Dungeoneer.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pedido realizado esta misma ma\u00f1ana a Dracotienda\u00a0aprovechando algunas de sus ofertas (por lo visto por su d\u00e9cimo aniversario) para aumentar mi ludoteca. Necesitaba aire fresco [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[6],"tags":[1875,20,1874,1872,1871,1873],"class_list":["post-16022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-ludoteca","tag-grimoire","tag-ludoteca","tag-mondo-sapiens","tag-province","tag-quest","tag-urbania"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/16022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=16022"}],"version-history":[{"count":1,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/16022\/revisions"}],"predecessor-version":[{"id":19443,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/16022\/revisions\/19443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/19442"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=16022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=16022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=16022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}