{"id":16036,"date":"2014-10-21T20:24:58","date_gmt":"2014-10-21T18:24:58","guid":{"rendered":"http:\/\/labsk.net\/wkr\/?p=16036"},"modified":"2015-06-06T16:16:16","modified_gmt":"2015-06-06T14:16:16","slug":"pixel-tactics-solomon-draft-mode","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/16036\/","title":{"rendered":"Pixel Tactics (Solomon Draft Mode)"},"content":{"rendered":"<p style=\"text-align: justify;\">Hoy probamos el <a href=\"http:\/\/www.lvl99games.com\/games\/pixeltactics\/wp-content\/uploads\/2013\/03\/PT-Supplemental-Rules-Draft-Mode.pdf\" target=\"_blank\">Duel Draft Mode<\/a>\u00a0(pdf) para <a href=\"http:\/\/www.lvl99games.com\/games\/pixeltactics\/\" target=\"_blank\">Pixel Tactics<\/a> y no nos convenci\u00f3 demasiado.\u00a0Volviendo a casa estuve pensando que draft (de los que conozco de magic) podr\u00eda funcionarle al juego sin que resultara demasiado tedioso y fuera relativamente sencillo.<br \/>\nY me he decantado por el Solomon Draft.<\/p>\n<p style=\"text-align: justify;\"><strong>SOLOMON DRAFT<\/strong><\/p>\n<p style=\"text-align: justify;\">Mezcla 2 sets de 25 cartas Pixel Tactics diferentes pero con el mismo reverso (por si usas fundas transparentes), para tener un mazo de 50 cartas diferentes y \u00fanicas. Yo por ejemplo, yo uso uno del Pixel Tactics 2 y uno del Pixel Tactics 3. Baraja las 50 cartas y crea un mazo de reparto.<\/p>\n<p style=\"text-align: justify;\"><strong>Se juega alternativamente por turnos 5 drafts<\/strong> comenzando por un jugador inicial (\u00e9chalo a suertes).<\/p>\n<p style=\"text-align: justify;\">Cada draft consiste en que el jugador activo <strong>roba 10 cartas del mazo de reparto<\/strong>, y con ellas debe formar dos grupos de cartas en cualquier combinaci\u00f3n de n\u00famero, y dejar que su oponente elija primero con que mont\u00f3n de los dos se queda, mientras que el restante ser\u00e1 para \u00e9l.<\/p>\n<p style=\"text-align: justify;\">Una vez se haya robado alternativamente 5 veces del mazo de reparto (50 cartas, por tanto), no quedaran cartas por repartir y el draft finaliza. Ten en cuenta que por la forma de dividir los grupos, los jugadores no tienen porque acabar con mazos de igual n\u00famero de cartas. As\u00ed que esto puede ser un handicap y tener su gracia.<\/p>\n<p style=\"text-align: justify;\">Al ser n\u00famero impar me da que pensar que igual el jugador inicial tiene una relativa ventaja, as\u00ed que el ser\u00e1 quien empiece a jugar la partida, el primer turno de la primera oleada de la primera ronda.<\/p>\n<p style=\"text-align: justify;\">Luego se juega un coto de partidas de forma habitual y con las reglas est\u00e1ndar.<\/p>\n<p style=\"text-align: justify;\"><strong>OPINI\u00d3N PERSONAL<\/strong><\/p>\n<p style=\"text-align: justify;\">Estamos ante un divertido problema cl\u00e1sico de matem\u00e1ticas de reparto de bot\u00edn. Si eres jug\u00f3n supongo que te vendr\u00e1 a la mente ahora juegos de mesa como San Marco (uno de mis favoritos de mayor\u00edas), Piece o\u2019 Cake, <a title=\"Smoking Guns v2\" href=\"http:\/\/labsk.net\/wkr\/archives\/14186\/\" target=\"_blank\">Smoking Guns<\/a>, o Bzzz\u2026, que explotan en sus mec\u00e1nicas una idea parecida.<\/p>\n<p style=\"text-align: justify;\">Este formato, aunque a simple vista parezca sencillo de ejecutar, puede ser muy complicado de jugar correctamente, ya que hay un mont\u00f3n de decisiones que tomar cada vez que se separan las cartas y se forman grupos de reparto con ellas.<\/p>\n<p style=\"text-align: justify;\">Una gran parte de la habilidad en este formato, es recordar a su vez, las cartas del oponente ha ido eligiendo y equilibrar las pilas de reparto para tomar ventaja de eso.\u00a0Por tanto, es indispensable conocer los 50 l\u00edderes y h\u00e9roes elegibles, y exige una veteran\u00eda en el juego.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n entra en funcionamiento la picaresca, el ser capaz de enga\u00f1ar a su oponente con un reparto a priori ventajoso para \u00e9l, pero que a la larga le suponga perder consistencia o sinergias. Hay que estar con diez ojos, valorar cu\u00e1les son las cartas que entran en el tipo de mazo que quiero hacerme, no sin dejar de pensar nunca que cartas pueden todav\u00eda estar pendientes de salir.<\/p>\n<p style=\"text-align: justify;\">Y luego, si tu mazo tiene menos de 25 cartas (las habituales en el juego est\u00e1ndar) ten en cuenta que tendr\u00e1s m\u00e1s posibilidades de robar esa carta que buscas, pero por contra, si no logras vencer a tu oponente r\u00e1pidamente tendr\u00e1s serios problemas cuando agotes el mazo.<\/p>\n<p style=\"text-align: justify;\"><strong>Si os gusta la idea o finalmente lo prob\u00e1is, dejadme un comentario con la experiencia.<\/strong> Nos leemos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy probamos el Duel Draft Mode\u00a0(pdf) para Pixel Tactics y no nos convenci\u00f3 demasiado.\u00a0Volviendo a casa estuve pensando que draft (de los que conozco de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-16036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos-de-mesa"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/16036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=16036"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/16036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/17804"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=16036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=16036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=16036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}