{"id":18541,"date":"2015-10-15T14:26:54","date_gmt":"2015-10-15T12:26:54","guid":{"rendered":"http:\/\/labsk.net\/wkr\/?p=18541"},"modified":"2015-10-25T11:55:43","modified_gmt":"2015-10-25T09:55:43","slug":"creacion-de-mazos-de-tiny-leaders-i","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/18541\/","title":{"rendered":"Creaci\u00f3n de mazos de Tiny Leaders (I)"},"content":{"rendered":"<p style=\"text-align: justify;\">Sigo con mi objetivo de montarme, poco a poco,\u00a0<a href=\"http:\/\/labsk.net\/wkr\/archives\/18071\/\" target=\"_blank\">un buen pu\u00f1ado de mazos de Tiny Leaders<\/a>, listos para ser elegidos y jugados. De momento tengo ya montados 13 mazos, y aunque tengo alg\u00fan l\u00edder todav\u00eda sin usar, en la caja que eleg\u00ed para guardar todo no me caben m\u00e1s, as\u00ed que tocar\u00e1 dar entrada y salida a algunos.<\/p>\n<p style=\"text-align: justify;\">Os voy a comentar, muy por encima, qu\u00e9 son las cosas que he tenido en cuenta para montar estos mazos (teniendo en cuenta que tengo una colecci\u00f3n limitada de cartas y que las \u00abmejores\u00bb las tengo en otros mazos que no quiero desmontar).<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline; color: #800000;\"><strong>El comandante<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Lo primero que hay que tener en cuenta en Tiny Leaders es que hace falta un\u00a0cambio radical de mentalidad; determinados conceptos del Magic m\u00e1s cl\u00e1sico son distintos en este formato, y cartas de\u00a0indudable calidad se vuelven menos poderosas en favor de otras que considerar\u00edamos injugables.<\/p>\n<p style=\"text-align: justify;\">Tampoco\u00a0podemos considerar la clasificaci\u00f3n cl\u00e1sica de mazos (Aggro, control, combo), ya que son los comandantes los\u00a0que determinan la estrategia y dictan las pautas del juego, incluso influyendo en los colores de nuestra\u00a0estrategia.<\/p>\n<p style=\"text-align: justify;\">Por tanto, creo que el primer paso para iniciarse <strong>es estudiar la estrategia de la pieza m\u00e1s importante\u00a0de un mazo de Tiny Leader: <a href=\"http:\/\/magiccards.info\/query?q=t%3A%22legendary%22+cmc%3C%3D3+t%3A%22creature%22&amp;v=card&amp;s=cname\" target=\"_blank\">su comandante<\/a><\/strong>.\u00a0B\u00e1sicamente, lo primero ha tener en cuenta es la mejor manera de explotar su habilidad (a ser posible infinitas veces).<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline; color: #800000;\"><strong>La caja de herramientas<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Las toolbox, o cajas de herramientas, son algunos conjuntos de cartas que, independientemente de la estrategia,\u00a0nos aportan un valor a\u00f1adido a la partida, y que, en general, desearemos tener siempre en todos nuestros mazos. En el\u00a0caso concreto de Tiny Leader, donde los mazos son, habitualmente, bicolores o tricolores, encontramos muchos\u00a0tipos de toolbox acordes a la porci\u00f3n del man\u00e1 elegida; Adem\u00e1s, existen tierras y artefactos sin coste coloro, lo\u00a0que hace que sean m\u00e1s f\u00e1ciles de incluir.<\/p>\n<p style=\"text-align: justify;\">En general, toda toolbox que se precie deber\u00eda incluir al menos cartas de estos apartados: odio contra el comandante enemigo, odio contra artefactos y encantamientos, filtradores\/generadores de mana, protecci\u00f3n de nuestro comandante, cartas indispensables (por su utilidad en relaci\u00f3n a su coste): y quiz\u00e1s eliminadores (removals)\u00a0masivos y banquillos indispensables.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline; color: #800000;\"><strong>Odio contra el comandante enemigo<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">B\u00e1sicamente, cartas que destruyen, exilian o lo env\u00edan a la biblioteca (o si el jugador lo prefiere a su zona de comandante).<\/p>\n<ul>\n<li style=\"text-align: justify;\">Para el color blanco tenemos:\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Camino+al+exilio&amp;v=card&amp;s=cname\" target=\"_blank\">Camino al exilio<\/a> (Path to exile), <a href=\"http:\/\/magiccards.info\/query?q=condenar&amp;v=card&amp;s=cname\" target=\"_blank\">Condenar<\/a> (Condemn), <a href=\"http:\/\/magiccards.info\/query?q=Anillo+del+Olvido&amp;v=card&amp;s=cname\" target=\"_blank\">Anillo del Olvido<\/a> (Oblivion Ring), \u00a0<a href=\"http:\/\/magiccards.info\/query?q=Espadas+en+guada%C3%B1as&amp;v=card&amp;s=cname\" target=\"_blank\">Espadas en guada\u00f1as<\/a> (Swords to Plowshares).<\/li>\n<li style=\"text-align: justify;\">Para el color azul:\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Hibridaci%C3%B3n+r%C3%A1pida&amp;v=card&amp;s=cname\" target=\"_blank\">Hibridaci\u00f3n r\u00e1pida<\/a> (Rapid Hybridization),\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Pongificar+&amp;v=card&amp;s=cname\" target=\"_blank\">Pongificar<\/a>\u00a0(Pongify), <a href=\"http:\/\/magiccards.info\/query?q=Cambio+de+realidad&amp;v=card&amp;s=cname\" target=\"_blank\">Cambio de realidad<\/a> (Reality Shift) y\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Forma+de+v%C3%ADbora&amp;v=card&amp;s=cname\" target=\"_blank\">Forma de v\u00edbora<\/a>\u00a0(Snakeform).<\/li>\n<li style=\"text-align: justify;\">Para el color negro:\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Golpe+a+la+garganta+&amp;v=card&amp;s=cname\" target=\"_blank\">Golpe a la garganta<\/a> (Go for the throat).\u00a0<a href=\"http:\/\/magiccards.info\/query?q=desmembrar&amp;v=card&amp;s=cname\" target=\"_blank\">Desmembrar<\/a> (Dismember), <a href=\"http:\/\/magiccards.info\/query?q=Producir+asfixia&amp;v=card&amp;s=cname\" target=\"_blank\">Producir asfixia<\/a> (Smother).<\/li>\n<li style=\"text-align: justify;\">Para el color rojo:\u00a0<a href=\"http:\/\/magiccards.info\/m11\/es\/149.html\" target=\"_blank\">Rel\u00e1mpago\u00a0<\/a>(Lightning). <a href=\"http:\/\/magiccards.info\/query?q=Morteros+de+m%C3%ADzzium&amp;v=card&amp;s=cname\" target=\"_blank\">Morteros de m\u00edzzium<\/a> (Mizzium Mortars).<\/li>\n<li style=\"text-align: justify;\">Para el color verde:\u00a0<a href=\"http:\/\/magiccards.info\/query?q=La+bestia+interior&amp;v=card&amp;s=cname\" target=\"_blank\">La bestia interior<\/a> (Beast within).\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Forma+de+v%C3%ADbora&amp;v=card&amp;s=cname\" target=\"_blank\">Forma de v\u00edbora<\/a>\u00a0(Snakeform),\u00a0<a href=\"http:\/\/magiccards.info\/bfz\/es\/184.html\" target=\"_blank\">En picado <\/a>(Plummet).<\/li>\n<li style=\"text-align: justify;\">Bicolores: <a href=\"http:\/\/magiccards.info\/cmd\/es\/231.html\" target=\"_blank\">Terminar<\/a> (Terminate). <a href=\"http:\/\/magiccards.info\/query?q=Deterioro+brusco&amp;v=card&amp;s=cname\" target=\"_blank\">Deterioro brusco<\/a> (Abrupt Decay), <a href=\"http:\/\/magiccards.info\/query?q=H%C3%A9lice+de+Rel%C3%A1mpagos&amp;v=card&amp;s=cname\" target=\"_blank\">H\u00e9lice de Rel\u00e1mpagos<\/a> (Lightning Helix), <a href=\"http:\/\/magiccards.info\/cmd\/es\/211.html\" target=\"_blank\">Mortificar<\/a> (Mortifice), <a href=\"http:\/\/magiccards.info\/query?q=pudrir&amp;v=card&amp;s=cname\" target=\"_blank\">Pudrir<\/a>\u00a0(Putrifice).<\/li>\n<li style=\"text-align: justify;\">Artefactos: <a href=\"http:\/\/magiccards.info\/query?q=Explosivos+dise%C3%B1ados&amp;v=card&amp;s=cname\" target=\"_blank\">Explosivos dise\u00f1ados<\/a> (Engineered Explosives), <a href=\"http:\/\/magiccards.info\/query?q=aguja+medular&amp;v=card&amp;s=cname\" target=\"_blank\">Aguja medular<\/a> (Pithin Needle).<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline; color: #800000;\"><strong>Odio contra artefactos y encantamientos<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Los artefactos en este formato son poderosos, sobre todo los que aceleradores de man\u00e1, y los encantamientos\u00a0molestos est\u00e1n a la orden del d\u00eda, y no siempre somos capaces de quit\u00e1rnoslos de en medio con facilidad. Por\u00a0eso, es recomendable tambi\u00e9n incluir unas cuantas copias de cartas capaces de deshacerse de esos inc\u00f3modos\u00a0permanentes.<\/p>\n<ul>\n<li style=\"text-align: justify;\">Para el color blanco tenemos: <a href=\"http:\/\/magiccards.info\/query?q=Desencantar&amp;v=card&amp;s=cname\" target=\"_blank\">Desencantar<\/a>\u00a0(Disenchant).<\/li>\n<li style=\"text-align: justify;\">Para el color rojo:\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Reguero+de+ruptura&amp;v=card&amp;s=cname\" target=\"_blank\">Reguero de ruptura<\/a> (Shattering spree).<\/li>\n<li style=\"text-align: justify;\">Para el color verde: <a href=\"http:\/\/magiccards.info\/query?q=naturalizar&amp;v=card&amp;s=cname\" target=\"_blank\">Naturalizar<\/a> (Naturalize).<\/li>\n<li style=\"text-align: justify;\">Bicolores:\u00a0<a href=\"http:\/\/magiccards.info\/cmd\/es\/211.html\" target=\"_blank\">Mortificar<\/a> (Mortifice), <a href=\"http:\/\/magiccards.info\/query?q=pudrir&amp;v=card&amp;s=cname\" target=\"_blank\">Pudrir<\/a>\u00a0(Putrifice).<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline; color: #800000;\"><strong>Filtradores\/generadores de mana<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">En \u00a0muchas ocasiones nuestro comandante ser\u00e1 tricolor, as\u00ed que si queremos adelantarnos a nuestro rival tendremos que acelerar de alguna manera nuestras fuentes de man\u00e1 o filtr\u00e1ndolas para obtener los colores adecuados en cada\u00a0momento (y no retrasar as\u00ed nuestra estrategia).<\/p>\n<p style=\"text-align: justify;\">Respecto al primer grupo, encontramos un conjunto de tierras y artefactos muy interesantes: <a href=\"http:\/\/magiccards.info\/query?q=Templo+de+la+Diosa+Falsa&amp;v=card&amp;s=cname\" target=\"_blank\">Templo\u00a0de la Diosa Falsa<\/a>, <a href=\"http:\/\/magiccards.info\/query?q=Lingote+de+Acero+Oscuro&amp;v=card&amp;s=cname\" target=\"_blank\">Lingote de Acero Oscuro<\/a>, <a href=\"http:\/\/magiccards.info\/query?q=Torre+de+Mando&amp;v=card&amp;s=cname\" target=\"_blank\">Torre de Mando<\/a> o las BounceLands (de Visiones o Ravnica).<\/p>\n<p style=\"text-align: justify;\">Como\u00a0representante del segundo grupo, tenemos el <a href=\"http:\/\/magiccards.info\/query?q=Prisma+Prof%C3%A9tico&amp;v=card&amp;s=cname\" target=\"_blank\">Prisma Prof\u00e9tico<\/a>, las Tierras V\u00edvidas (de Lorwyn), las tierras Filtradoras, las\u00a0Fetch lands (tanto las \u201cbuenas y caras\u201d, como las de Fragmentos de Alara (menci\u00f3n especial a las tricolores), las pain lands, o las buscadoras Expansi\u00f3n Terram\u00f3rfica \/ Terrenos\u00a0expansivos.\u00a0Menci\u00f3n especial a la <a href=\"http:\/\/magiccards.info\/query?q=Gaea%27s+Cradle&amp;v=card&amp;s=cname\" target=\"_blank\">Gaea&#8217;s Cradle<\/a>, pero que por su precio actual es inasumible para la mayor\u00eda de bolsillos.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline; color: #800000;\"><strong>Protecci\u00f3n para nuestro comandante<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Muchas veces desearemos que nuestro comandante permanezca en el campo de batalla el mayor tiempo\u00a0posible, y eso implica protecci\u00f3n mediante artefactos\/equipos, instant\u00e1neos o encantamientos, o cartas que le proporcionen velo (shroud) o antimaleficio (hexproof). Los mejores ejemplos de artefactos son\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Grebas+Rel%C3%A1mpago&amp;v=card&amp;s=cname\" target=\"_blank\">Grebas Rel\u00e1mpago<\/a>\u00a0(Lightning Greaves), <a href=\"http:\/\/magiccards.info\/query?q=Manto+de+sedasusurrante&amp;v=card&amp;s=cname\" target=\"_blank\">Manto de sedasusurrante<\/a>\u00a0(Whispersilk Cloak),\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Casco+del+Campe%C3%B3n&amp;v=card&amp;s=cname\" target=\"_blank\">Casco del Campe\u00f3n<\/a>, <a href=\"http:\/\/magiccards.info\/query?q=Astucia+del+Guardabosque&amp;v=card&amp;s=cname\" target=\"_blank\">Astucia del Guardabosque<\/a>, <a href=\"http:\/\/magiccards.info\/query?q=Autoridad+del+Alfa&amp;v=card&amp;s=cname\" target=\"_blank\">Autoridad del Alfa<\/a>. Instant\u00e1neos tenemos <a href=\"http:\/\/magiccards.info\/sc\/es\/16.html\" target=\"_blank\">Luz de oropel<\/a>,\u00a0<a href=\"http:\/\/magiccards.info\/on\/es\/91.html\" target=\"_blank\">Astucia de la maga<\/a>,\u00a0<a href=\"http:\/\/magiccards.info\/bok\/en\/59.html\" target=\"_blank\">Veil of Secrecy<\/a>,\u00a0<a href=\"http:\/\/magiccards.info\/rtr\/es\/45.html\">Piel de m\u00edzzium<\/a>,\u00a0<a href=\"http:\/\/magiccards.info\/m15\/es\/193.html\">Astucia del guardabosque<\/a>,\u00a0<a href=\"http:\/\/magiccards.info\/avr\/es\/192.html\">Palabra protectora<\/a>\u00a0o\u00a0<a href=\"http:\/\/magiccards.info\/gtc\/es\/195.html\">Amuleto simic<\/a>.\u00a0En ocasiones incluso, alguna criatura, por ejemplo, <a href=\"http:\/\/magiccards.info\/query?q=Madre+de+las+Runas&amp;v=card&amp;s=cname\" target=\"_blank\">Madre de las Runas<\/a>.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline; color: #800000;\"><strong>Cartas indispensables<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Estas cartas, que son por s\u00ed solas tan buenas, que tienen cabida en casi cualquier mazo:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Para negro:\u00a0<a href=\"http:\/\/magiccards.info\/query?q=+Inquisici%C3%B3n+de+Kozilek&amp;v=card&amp;s=cname\" target=\"_blank\">Inquisici\u00f3n de Kozilek<\/a> (Inquisition of Kozilek), <a href=\"http:\/\/magiccards.info\/query?q=Liliana+del+velo&amp;v=card&amp;s=cname\" target=\"_blank\">Liliana del Velo<\/a> (Liliana of the Veil),\u00a0\u00a0<a href=\"http:\/\/magiccards.info\/query?q=+Cenit+del+sol+negro&amp;v=card&amp;s=cname\" target=\"_blank\">Cenit del sol negro<\/a> (Black Sun&#8217;s Zenith),\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Confidente+oscuro&amp;v=card&amp;s=cname\" target=\"_blank\">Confidente oscuro<\/a> (Dark Confidant), <a href=\"http:\/\/magiccards.info\/query?q=coacci%C3%B3n&amp;v=card&amp;s=cname\" target=\"_blank\">Coacci\u00f3n <\/a>(Duress).<\/li>\n<li style=\"text-align: justify;\">Para blanco: <a href=\"http:\/\/magiccards.info\/query?q=M%C3%ADstica+fragua+de+piedra+&amp;v=card&amp;s=cname\" target=\"_blank\">M\u00edstica fragua de piedra<\/a>\u00a0(Stoneforge Mystic).<\/li>\n<li style=\"text-align: justify;\">Para azul: <a href=\"http:\/\/magiccards.info\/query?q=N%C3%A9mesis+de+nombre+verdadero&amp;v=card&amp;s=cname\" target=\"_blank\">N\u00e9mesis de nombre verdadero<\/a>, <a href=\"http:\/\/magiccards.info\/query?q=hojalatera&amp;v=card&amp;s=cname\" target=\"_blank\">Hojalatera<\/a> (Tinker). Cantrips (del estilo de Brainstorm, ponder, preordain, serum visions, y\u00a0gitaxian probe),\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Blue+Sun%27s+Zenith+&amp;v=card&amp;s=cname\" target=\"_blank\">Blue Sun&#8217;s Zenith<\/a>.<\/li>\n<li style=\"text-align: justify;\">Para rojo: <a href=\"http:\/\/magiccards.info\/query?q=Eidol%C3%B3n+del+gran+fest%C3%ADn&amp;v=card&amp;s=cname\" target=\"_blank\">Eidol\u00f3n del gran fest\u00edn<\/a>\u00a0(Eidolon of the Great Revel), <a href=\"http:\/\/magiccards.info\/query?q=luna+de+sangre&amp;v=card&amp;s=cname\" target=\"_blank\">Luna de sangre<\/a>\u00a0(Blood Moon).<\/li>\n<li style=\"text-align: justify;\">Para verde: <a href=\"http:\/\/magiccards.info\/m13\/es\/185.html\" target=\"_blank\">Rencor<\/a> (Rancor), <a href=\"http:\/\/magiccards.info\/query?q=biblioteca+Silvana&amp;v=card&amp;s=cname\" target=\"_blank\">Biblioteca\u00a0Silvana<\/a> (Sylvan Library), <a href=\"http:\/\/magiccards.info\/query?q=Aves+del+para%C3%ADso&amp;v=card&amp;s=cname\" target=\"_blank\">Aves del Para\u00edso<\/a>\u00a0(Birds of Paradise), <a href=\"http:\/\/magiccards.info\/query?q=Elfos+de+Llanowar&amp;v=card&amp;s=cname\" target=\"_blank\">Elfos de Llanowar<\/a> (Llanowar Elves),\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Anciano+de+la+tribu+Sakura&amp;v=card&amp;s=cname\" target=\"_blank\">Anciano de la tribu Sakura<\/a>\u00a0(Sakura-Tribe Elder), <a href=\"http:\/\/magiccards.info\/c14\/es\/199.html\" target=\"_blank\">Gradar<\/a> (Harrow),\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Green+Sun%27s+Zenith&amp;v=card&amp;s=cname\" target=\"_blank\">Green Sun&#8217;s Zenith<\/a>.<\/li>\n<li style=\"text-align: justify;\">Bicolor: <a href=\"http:\/\/magiccards.info\/gp\/es\/106.html\" target=\"_blank\">Castigar<\/a>\u00a0(Castigate),\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Lim-D%C3%BBl%27s+Vault&amp;v=card&amp;s=cname\" target=\"_blank\">Lim-D\u00fbl&#8217;s Vault<\/a>,\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Ashiok%2C+Nightmare+Weaver&amp;v=card&amp;s=cname\" target=\"_blank\">Ashiok, Nightmare Weaver<\/a>.<\/li>\n<li style=\"text-align: justify;\">Artefactos:\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Trompo+adivinador+del+sensei&amp;v=card&amp;s=cname\" target=\"_blank\">Trompo adivinador del sensei<\/a>\u00a0(Sensei\u2019s Divining Top).<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline; color: #800000;\"><strong>Eliminadores masivos<\/strong><\/span><\/p>\n<p>Para limpiar la mesa de criaturas cuando la cosa se pone fea:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Para el color rojo tenemos: <a href=\"http:\/\/magiccards.info\/query?q=Rolling+earthquake&amp;v=card&amp;s=cname\" target=\"_blank\">Terremoto rodante<\/a> (Rolling earthquake) que es una versi\u00f3n mejorada de <a href=\"http:\/\/magiccards.info\/cmd\/en\/121.html\" target=\"_blank\">Terremoto<\/a>, <a href=\"http:\/\/magiccards.info\/query?q=c%C3%B3lera+de+los+dioses&amp;v=card&amp;s=cname\" target=\"_blank\">C\u00f3lera de los dioses<\/a> (Anger of the Gods), <a href=\"http:\/\/magiccards.info\/query?q=+Detonaci%C3%B3n+%C3%ADgnea&amp;v=card&amp;s=cname\" target=\"_blank\">Detonaci\u00f3n \u00edgnea<\/a> (Pyroclasm), <a href=\"http:\/\/magiccards.info\/query?q=Tormenta+de+escoria&amp;v=card&amp;s=cname\" target=\"_blank\">Tormenta de escoria<\/a>\u00a0(Slagstorm),\u00a0<a href=\"http:\/\/magiccards.info\/query?q=Morteros+de+m%C3%ADzzium&amp;v=card&amp;s=cname\" target=\"_blank\">Morteros de m\u00edzzium<\/a> (Mizzium Mortars).<\/li>\n<li style=\"text-align: justify;\">Para el color verde: <a href=\"http:\/\/magiccards.info\/query?q=Hurac%C3%A1n&amp;v=card&amp;s=cname\" target=\"_blank\">Hurac\u00e1n<\/a>, <a href=\"http:\/\/magiccards.info\/ktk\/es\/157.html\">Tormenta de viento<\/a>.<\/li>\n<li style=\"text-align: justify;\">Para el color negro: <a href=\"http:\/\/magiccards.info\/query?q=Toxic+Deluge&amp;v=card&amp;s=cname\" target=\"_blank\">Diluvio t\u00f3xico<\/a> (Toxic deluge).<\/li>\n<li style=\"text-align: justify;\">Para el color blanco:\u00a0<a href=\"http:\/\/magiccards.info\/query?q=colapso+de+planos&amp;v=card&amp;s=cname\" target=\"_blank\">Collapso de Planos<\/a>\u00a0(Planar Collapse).<\/li>\n<li style=\"text-align: justify;\">Artefactos: <a href=\"http:\/\/magiccards.info\/query?q=+Bomba+trinquete&amp;v=card&amp;s=cname\" target=\"_blank\">Bomba trinquete<\/a> (Ratched Bomb), <a href=\"http:\/\/magiccards.info\/query?q=Acci%C3%B3n+perniciosa&amp;v=card&amp;s=cname\" target=\"_blank\">Acci\u00f3n Perniciosa<\/a> (Pernicious Deed).<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline; color: #800000;\"><strong>Anti-protecciones<\/strong><\/span><\/p>\n<p>Si alguna criatura tiene protecci\u00f3n contra un color, tendr\u00e1s que tirar de sacrificios.<\/p>\n<ul>\n<li>Para el color negro tenemos: <a href=\"http:\/\/magiccards.info\/query?q=Innocent+blood&amp;v=card&amp;s=cname\" target=\"_blank\">Sangre inocente<\/a> (Innocent blood).<\/li>\n<li>Para blanco: <a href=\"http:\/\/magiccards.info\/query?q=+Fulgor+Celestial+&amp;v=card&amp;s=cname\" target=\"_blank\">Fulgor Celestial<\/a> (Celestial Flare).<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline; color: #800000;\"><strong>Banquillos indispensables<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Ese banquillo que no debe faltar nunca. Odio contra un color concreto (que nos haga especialmente pupa a nuestro Comandante o nuestra estrategia), cartas que se lo pongan dif\u00edcil contra estrategias concretas, cartas de odio contra criaturas peque\u00f1as (<a href=\"http:\/\/magiccards.info\/query?q=dise%C3%B1ada&amp;v=card&amp;s=cname\" target=\"_blank\">Peste dise\u00f1ada<\/a>), cartas que puedan ganar ellas solas, cartas para jugar al despiste, y el sempiterno\u00a0<a href=\"http:\/\/magiccards.info\/query?q=elixir+de+inmortalidad&amp;v=card&amp;s=cname\" target=\"_blank\">Elixir de Inmortalidad<\/a>.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em><strong>Nota.<\/strong> Ir\u00e9 actualizando esta entrada\u00a0conforme vaya descubriendo o recordando m\u00e1s cartas.<\/em><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Sigo con mi objetivo de montarme, poco a poco,\u00a0un buen pu\u00f1ado de mazos de Tiny Leaders, listos para ser elegidos y jugados. De momento tengo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[954,689,76,1950],"class_list":["post-18541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos-de-mesa","tag-casual","tag-formato","tag-magic","tag-tiny-leaders"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/18541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=18541"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/18541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/18476"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=18541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=18541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=18541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}