{"id":19757,"date":"2017-05-19T14:19:36","date_gmt":"2017-05-19T13:19:36","guid":{"rendered":"http:\/\/labsk.net\/wkr\/?p=19757"},"modified":"2017-05-19T14:20:38","modified_gmt":"2017-05-19T13:20:38","slug":"black-hills-resena","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/19757\/","title":{"rendered":"Black Hills (rese\u00f1a)"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/zacatrus.es\/black-hills.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Zacatrus<\/strong><\/a> nos trae un juego de gesti\u00f3n de recursos para toda la familia, ambientado en el Salvaje Oeste, que pueden disfrutar tanto jugadores experimentados como casuales. <a href=\"https:\/\/boardgamegeek.com\/boardgame\/205819\/black-hills\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Black Hills<\/strong><\/a> es un\u00a0un sencillo juego de recursos, dise\u00f1ado por <b>Al Garc\u00eda<\/b>, donde prima la interacci\u00f3n entre los jugadores y sobre todo destaca por un arte diferente a lo que nos tienen acostumbrados (sin duda lo m\u00e1s destacable).<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>COMPONENTES<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Muy dignos. Las cartas son de tama\u00f1o no est\u00e1ndar (puedes usar las Asia de Zacatrus) y es recomendable enfundarlas. Los personajes son bastante rompedores, siempre en tres tintas (blanco, negro, rojo). Los eventos, algo m\u00e1s austeros, no disponen de grandes ilustraciones. El reglamento, breve, pero bien explicado. Quiz\u00e1s hay demasiado texto para lo que luego es realmente el juego. Un peque\u00f1o tablero de buen carton\u00e9 y contadores de madera con diferentes formas para los recursos (madera, pieles, oro), la chapa de Sheriff y las fichas de jugadores y marcadores. \u00a0Su PVP es\u00a016,50 \u20ac, precio m\u00e1s que justo para lo que contiene.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19759\" src=\"http:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills2.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills2.jpg 600w, https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills2-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>SINOPSIS<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">El juego transcurre en 1876, en plena <strong>Fiebre del Oro. <\/strong>La ciudad de<strong> Black Hills\u00a0<\/strong>es un hervidero de aventureros, buscadores de oro, renegados, colonos y cowboys en busca de riqueza. Es tal el caos que la ciudad\u00a0necesita un alcalde poderoso, que devuelva a la ciudad al imperio de la ley.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #800000;\">OBJETIVO DEL JUEGO<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">El objetivo de los jugadores es conseguir los<strong> 5 puntos de reputaci\u00f3n<\/strong> necesarios para ser investido como alcalde y ser el vencedor de la partida. Para ello hay que invertir recursos en la ciudad (o bien 3 pieles, o bien 1 oro y 2 maderas).<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #800000;\"><strong>DESARROLLO DE UNA PARTIDA<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Preparaci\u00f3n.<\/strong> Al principio de cada Ronda se reparten 4 cartas de Personaje y 1 carta de Evento (siempre y cuando no tenga ya dos eventos en su mano) a cada jugador. El jugador decide con qu\u00e9 dos personajes se queda en su mano para esa Ronda, y descarta los otros en secreto (debajo del mazo).<\/p>\n<p style=\"text-align: justify;\">Cada Ronda se juega por turnos alternadamente y empieza a jugarla el Sheriff (quien tenga la chapa). En su turno cada jugador puede jugar una carta de Personaje (y dejarla enfrente de \u00e9l), jugar (activar) una carta de evento y\/o realizar un asalto con un pistolero. No es posible pasar.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Personajes.<\/strong> Las cartas de Personaje pueden ser de varios tipos: Aventureros (que sirven para obtener recursos), Colonos (que sirven para invertir en la ciudad y hacer alguna acci\u00f3n) y los Personajes Especiales (que tienen habilidades \u00fanicas). Las habilidades de los Personajes son obligatorias (siempre y cuando se puedan hacer).\u00a0Mineros, la madame de la ciudad, el forajido, el jefe indio\u2026 todos estos personajes cl\u00e1sicos de los Western de sobremesa nos servir\u00e1n para hacernos un nombre, conseguir recursos o rob\u00e1rselos a nuestros contrincantes.<\/li>\n<li style=\"text-align: justify;\"><strong>Eventos.<\/strong> Las cartas de Eventos sirven para realizar algo distinto (incluso obtener puntos de reputaci\u00f3n). Algunas requieren el pago de oro para su activaci\u00f3n. Una vez activada, se ejecuta su habilidad obligatoriamente y permanece frente a \u00e9l, hasta el final de la Ronda. Solo se puede activar una carta de Evento por turno.<\/li>\n<li style=\"text-align: justify;\"><strong>Asaltos.<\/strong> Un jugador que tenga un pistolero (al principio de la partida se comienzan con tantos pistoleros en la c\u00e1rcel como n\u00famero de jugadores) puede devolverlo a la c\u00e1rcel y lanzar el dado de punter\u00eda para ver cu\u00e1ntos recursos consigue como bot\u00edn (puede ser cero, uno o dos) que roba a cualquier otro jugador en cualquier combinaci\u00f3n. Los pistoleros se pueden obtener con el Personaje de Forajido y con el Evento Huida de la c\u00e1rcel.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Fin de Ronda.<\/strong> Cuando todos los jugadores han jugado sus dos turnos (que no son consecutivos) y han jugado, por tanto, dos personajes, la Ronda finaliza. Se descartan los eventos jugados. Todos los personajes vuelven al mazo, que se vuelve a barajar. Nunca se puede almacenar de una ronda a otra m\u00e1s de cinco recursos (as\u00ed que si tienes m\u00e1s, tendr\u00e1s que descartar).<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19760\" src=\"http:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills3.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills3.jpg 600w, https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills3-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #800000;\">PROS<\/span><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Un filler simp\u00e1tico (en la caja reza 40 minutos, pero yo no he jugado ninguna que supere los 20).<\/li>\n<li style=\"text-align: justify;\">Precio ajustado (menos de 17\u20ac).<\/li>\n<li style=\"text-align: justify;\">Para todos los p\u00fablicos.<\/li>\n<li style=\"text-align: justify;\">Sencillo de explicar, aprender y jugar.<\/li>\n<\/ul>\n<p><span style=\"color: #800000;\"><strong>CONTRAS<\/strong><\/span><\/p>\n<ul>\n<li>Para dos jugadores creo que falta interacci\u00f3n (ver m\u00e1s adelante una sencilla variante que propongo).<\/li>\n<li>No es un juego para jugar a todas las horas, o acabar\u00e1s quem\u00e1ndolo a los tres d\u00edas. En ese aspecto, no le veo mucho recorrido o rejugabilidad.<\/li>\n<li>Me hubiera gustado m\u00e1s que el tablero, se conformar\u00e1 con cartas (de esta manera ser\u00eda un juego mucho m\u00e1s portable).<\/li>\n<li>No est\u00e1 disponible para descarga las reglas en PDF.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19758\" src=\"http:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills.jpg 600w, https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2017\/05\/blackhills-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #800000;\">OPINI\u00d3N PERSONAL<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Un juego ideal para desintoxicar entre partidas o para jugar en a la hora de caf\u00e9. Esta bien conformado y dise\u00f1ado. Bien explicado y sin lagunas importantes. Considero que hay suficiente interacci\u00f3n (salvo para dos jugadores). Si puedes poner una banda sonora de Ennio Morricone para ambientar much\u00edsimo mejor (mi favorita Por un pu\u00f1ado de d\u00f3lares).<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><strong>Modo 2 jugadores.<\/strong><\/span> Para dos jugadores me he encontrado que la interacci\u00f3n se reduce bastante y puede haber bucles \u00abun poco feos\u00bb. Al repartir solo 8 personajes cada Ronda, ocurre que m\u00e1s de la mitad no aparecen en la Ronda. Puede ocurrir incluso, que haya Personajes que no aparezcan en la partida nunca. No ser\u00eda un problema sino fuera porque hay dos Personajes (en mi opini\u00f3n) que son clave para el desarrollo del juego, que son el Sheriff y el Forajido. Si en una partida no aparece nunca el Sheriff, siempre ser\u00e1 el jugador inicial cada Ronda la misma persona (con permiso del Evento de Ayudante del Sheriff) y eso es demasiada ventaja; y si no hay Forajido, ser\u00e1 complicado que se puedan realizar \u00absuficientes\u00bb asaltos con pistoleros. As\u00ed que, yo en mis partidas para dos jugadores he decidido retirar 4 Personajes y no jugar con ellos (para as\u00ed alterar la probabilidad de aparici\u00f3n) y fomentar \u00abla enjundia\u00bb. Tras meditarlo un poco decid\u00ed quitar el Comerciante, Predicador, Ingeniero y Explorador. La otra opci\u00f3n ser\u00eda jugar con un dummy, pero me convence menos.<\/p>\n<p style=\"text-align: justify;\">Si no tienes suficiente con esta rese\u00f1a, Zacatrus ha subido un\u00a0<strong><a href=\"https:\/\/www.youtube.com\/watch?v=NCs3cR65tA8\">v\u00eddeo<\/a><\/strong> donde da a conocer el juego con el autor, un <strong><a href=\"https:\/\/www.youtube.com\/watch?v=Fjgqdo2PYlo\">segundo<\/a>\u00a0<\/strong>con una peque\u00f1a partida entre los dos y una <strong><a href=\"https:\/\/www.youtube.com\/watch?v=nJexNZrYLlQ\">entrevista<\/a><\/strong> a fondo a <strong>Al Garc\u00eda<\/strong>.<\/p>\n<p style=\"text-align: justify;\">PD. Agradezco a Zacatrus la copia cedida desinteresamente para la elaboraci\u00f3n de esta rese\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zacatrus nos trae un juego de gesti\u00f3n de recursos para toda la familia, ambientado en el Salvaje Oeste, que pueden disfrutar tanto jugadores experimentados como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[2063,13,907],"class_list":["post-19757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos-de-mesa","tag-black-hills","tag-resena","tag-zacatrus"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/19757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=19757"}],"version-history":[{"count":2,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/19757\/revisions"}],"predecessor-version":[{"id":19764,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/19757\/revisions\/19764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/19761"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=19757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=19757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=19757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}