{"id":2004,"date":"2007-04-09T10:43:12","date_gmt":"2007-04-09T09:43:12","guid":{"rendered":"http:\/\/www.labsk.net\/wkr\/archives\/2004"},"modified":"2009-01-25T13:06:30","modified_gmt":"2009-01-25T12:06:30","slug":"guitar-zero-poseido-por-el-espiritu-de-jimmi-hendrix","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/2004\/","title":{"rendered":"Guitar Zero, pose\u00eddo por el esp\u00edritu de Jimmi Hendrix"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/static.zooomr.com\/images\/942325_f64d3b07af_o.jpg\" width=\"320\" height=\"240\" border=\"0\" alt=\"\" \/><\/p>\n<p>Este fin de semana ha sido sab\u00e1tico. Quer\u00eda haber terminado mi pr\u00f3xima <a href=\"http:\/\/reto50.labsk.net\" target=\"_blank\" >adaptaci\u00f3n para icehouse del reto 50<\/a> pero no pudo ser, he estado pose\u00eddo por el esp\u00edritu de Jimmi Hendrix meti\u00e9ndole al Guitar Zero, una versi\u00f3n gratuita del <a href=\"http:\/\/es.wikipedia.org\/wiki\/Guitar_Hero\" target=\"_blank\" >Guitar Hero<\/a> para PC. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/static.zooomr.com\/images\/942324_af279828cf_o.jpg\" width=\"320\" height=\"240\" border=\"0\" alt=\"\" \/><\/p>\n<p>Hace tiempo que conoc\u00eda el <a href=\"http:\/\/es.wikipedia.org\/wiki\/Frets_on_fire\" target=\"_blank\" >Frets on Fire<\/a>, el primer emulador para PC del Guitar Hero de PSX\/Xbox, pero este fin de semana di por casualidad con un \u00abnuevo\u00bb emulador llamado Guitar Zero que aunque esta en su versi\u00f3n alpha, realmente es bastante bueno.<\/p>\n<p><object width=\"425\" height=\"350\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/X4BbQ0SXoLQ\"><\/param><param name=\"wmode\" value=\"transparent\"><\/param><embed src=\"http:\/\/www.youtube.com\/v\/X4BbQ0SXoLQ\" type=\"application\/x-shockwave-flash\" wmode=\"transparent\" width=\"425\" height=\"350\"><\/embed><\/object><\/p>\n<p><a href=\"http:\/\/www.youtube.com\/watch?v=X4BbQ0SXoLQ\" target=\"_blank\" >http:\/\/www.youtube.com\/watch?v=X4BbQ0SXoLQ<\/a><\/p>\n<p>Para el que no sepa de que estoy hablando se trata de un videojuego en el que simulas ser un virtuoso de la guitarra (el\u00e9ctrica, se sobreentiende) y te permite tocar infinidad canciones.<\/p>\n<p>El videojuego esta preparado para jugarse con un mando guitarra, as\u00ed que si no dispones de uno (lo m\u00e1s habitual del mundo si no eres fan del Guitar Hero, tienes consola y te has gastado 75 EUR en una) debes usar el PPJoy para simular ese mando en el PC y usar el teclado como una <a href=\"http:\/\/es.wikipedia.org\/wiki\/Gibson_SG\" target=\"_blank\" >Gibson SG<\/a>. A mi cost\u00f3 configurarlo bien, as\u00ed que no desesperes.<\/p>\n<p>Te dejo <a href=\"http:\/\/www.box.net\/shared\/z8mq523hhr\" target=\"_blank\" >aqu\u00ed<\/a> mi configuraci\u00f3n y las instrucciones de instalaci\u00f3n\/uso, por si puede servirte. Basta con que sobreescribas el fichero config del guitar zero y uses el ini como configuraci\u00f3n del PPJoy. Tambi\u00e9n tienes un fichero que te explica como instalar el PPJoy y las teclas que usar\u00e1 el Guitar Zero con mi configuraci\u00f3n.<\/p>\n<p><b>Edito:<\/b> Aqu\u00ed os explica como <a href=\"http:\/\/taringa.net\/posts\/juegos\/959891\/Guitar-Zero-con-Teclado-%5BTuto+Game+Songs%5D.html\" target=\"_blank\" >configurar el ppjoy<\/a> tambi\u00e9n.<\/p>\n<p>Si quieres m\u00e1s canciones te recomiendo que busques por los trackers y buscadores de torrents (mininova, piratebay, torrentz, etc) all\u00ed hay packs de canciones hasta aburrirte, aunque te adelanto que muchas son aut\u00e9nticas fumadas hechas por aficionados, y si aun as\u00ed no tienes bastante existe un programa llamado ModPack que transforma las canciones del frets on fire al guitar zero.<\/p>\n<p><b>ENLACES:<\/b><\/p>\n<p><b>Guitar Zero (el videojuego)<\/b><br \/><a href=\"http:\/\/www.stepmaniamedia.com\/index.php?id=guitarzero\" target=\"_blank\" >http:\/\/www.stepmaniamedia.com\/index.php?id=guitarzero<\/a><br \/><a href=\"http:\/\/www.ddrspain.com\/download-598-Emulador-Guitar-Hero-1.21-alpha.html\" target=\"_blank\" >http:\/\/www.ddrspain.com\/download-598-Em &#8230; alpha.html<\/a><\/p>\n<p><b>Plugins<\/b><br \/><a href=\"http:\/\/www.ddrspain.com\/dc127-Plugins.html\" target=\"_blank\" >http:\/\/www.ddrspain.com\/dc127-Plugins.html<\/a><\/p>\n<p><b>Packs de Canciones del Guitar Hero<\/b><br \/><a href=\"http:\/\/www.ddrspain.com\/download-600-Guitar-Hero-I-+-Mod-GZ-para-GH1-y-GH2.html\" target=\"_blank\" >http:\/\/www.ddrspain.com\/download-600-Gu &#8230; y-GH2.html<\/a><br \/><a href=\"http:\/\/www.ddrspain.com\/download-606-Guitar-Hero-II-+-Mod-GZ-para-GH1-y-GH2.html\" target=\"_blank\" >http:\/\/www.ddrspain.com\/download-606-Gu &#8230; y-GH2.html<\/a><\/p>\n<p><b>PPJoy<\/b><br \/><a href=\"http:\/\/www.ddrspain.com\/download-599-GZ-Keyboard---PP-Joy.html\" target=\"_blank\" >http:\/\/www.ddrspain.com\/download-599-GZ &#8230; P-Joy.html<\/a><\/p>\n<p>Ale, a disfrutar con este pedazo juego. Espero volver a ser persona en unos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana ha sido sab\u00e1tico. Quer\u00eda haber terminado mi pr\u00f3xima adaptaci\u00f3n para icehouse del reto 50 pero no pudo ser, he estado pose\u00eddo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[17],"class_list":["post-2004","post","type-post","status-publish","format-standard","hentry","category-videojuegos","tag-pc"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/2004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=2004"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/2004\/revisions"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=2004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=2004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=2004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}