{"id":20517,"date":"2021-11-12T16:47:21","date_gmt":"2021-11-12T15:47:21","guid":{"rendered":"https:\/\/labsk.net\/wkr\/?p=20517"},"modified":"2021-11-12T16:50:35","modified_gmt":"2021-11-12T15:50:35","slug":"los-hijos-del-viento","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/20517\/","title":{"rendered":"Los hijos del viento"},"content":{"rendered":"\n<p class=\"justify-text wp-block-paragraph\"><strong>Los hijos del viento <\/strong>ha sido especialmente dise\u00f1ada para usarse con el reglamento de <strong>Aventuras en la Marca del Este. <\/strong>No obstante, puede ser empleado en Cl\u00e1sicos de la Marca, Leyendas de la Marca u otros juegos similares con relativa facilidad y aplicando pocos cambios. Adem\u00e1s, para su elaboraci\u00f3n se ha usado material que se encuentra en el Manual Avanzado (Caja Verde), Gazetteer y la aventura X2 &#8211; El Arca de los Mil Inviernos.<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">La historia transcurre en el <strong>remoto reino de Shui<\/strong> en la frontera del imperio Kang con Losang, en el valle donde se asienta y las imponentes monta\u00f1as que lo rodean. Un lugar m\u00e1gico que ha permanecido encerrado en s\u00ed mismo, lo que ha permitido que conserve casi intacto su misticismo y su estilo de vida tradicional.  <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Esta aventura est\u00e1 dise\u00f1ada para un grupo de entre 3 y 5 aventureros, de niveles 6 a 10, con un total combinado de unos 25-30 niveles de experiencia. Si decides no usar los personajes pregenerados, deber\u00eda haber al menos un mago, un cl\u00e9rigo o un palad\u00edn, y algunos personajes expertos en supervivencia como exploradores y druidas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote justify-text is-layout-flow wp-block-quote-is-layout-flow\"><p>He disfrutado mucho escribi\u00e9ndola. Esta bastante documentada, en mi l\u00ednea. Es algo at\u00edpica, tanto por la forma de estructurarse como por la forma de jugarse. Se divide b\u00e1sicamente en dos partes con distintos protagonistas, g\u00e9neros y tonos diferentes. Deseo que guste.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los hijos del viento ha sido especialmente dise\u00f1ada para usarse con el reglamento de Aventuras en la Marca del Este. No obstante, puede ser empleado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20518,"comment_status":"open","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-20517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/20517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=20517"}],"version-history":[{"count":4,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/20517\/revisions"}],"predecessor-version":[{"id":20523,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/20517\/revisions\/20523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/20518"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=20517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=20517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=20517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}