{"id":20704,"date":"2022-01-15T08:27:53","date_gmt":"2022-01-15T07:27:53","guid":{"rendered":"https:\/\/labsk.net\/wkr\/?p=20704"},"modified":"2022-01-15T08:30:24","modified_gmt":"2022-01-15T07:30:24","slug":"campos-de-accion-de-sid-sackson","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/20704\/","title":{"rendered":"Campos de acci\u00f3n, de Sid Sackson"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un juego de estrategia para dos jugadores de Sid Sackson.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong> <\/strong><u><span class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>MATERIALES<\/strong><\/span><\/u><\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Un tablero de ajedrez y dos juegos de damas de 12 piezas cada uno (12 fichas blancas y 12 fichas negras). Cada juego de fichas debe estar numerado del 1 al 12 (se recomienda utilizar pegatinas circulares).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span><span class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"\"><u style=\"font-weight: bold;\">PREPARACI\u00d3N<\/u><\/span><\/span> <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Coloca las piezas en el tablero como se indica en el diagrama. Elige qui\u00e9n jugar\u00e1 primero de la manera que m\u00e1s te convenga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong><u><span class=\"has-inline-color has-vivid-cyan-blue-color\">DESARROLLO DEL JUEGO<\/span><\/u><\/strong><\/strong><\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Por turnos, cada jugador mueve una de sus piezas en cualquier direcci\u00f3n (horizontal, vertical o diagonal). Una pieza <strong>debe <\/strong>mover exactamente tantos espacios como piezas (de cualquier color) haya junto a ella al comienzo de su turno. Mientras se mueve, una pieza puede pasar por encima de piezas de uno o ambos colores. Una pieza no puede aterrizar sobre una pieza amiga; pero puede aterrizar sobre una pieza enemiga, que entonces es capturada y retirada del juego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"\"><span class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"\"><u style=\"font-weight: bold;\">EJEMPLOS<\/u><\/span><\/span> <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">En el diagrama inicial, la pieza 9 de las blancas, que s\u00f3lo toca a otra pieza, puede moverse a cualquiera de los espacios marcados con A. La pieza 12 blanca, que toca tres piezas, puede moverse a B, C, D o E. Despu\u00e9s de mover la pieza 12 a C donde toca dos piezas, las blancas amenazan con capturar a las negras 11 (aunque las negras 11 podr\u00edan capturar en C primero). Despu\u00e9s de mover 12 a E, las blancas amenazan con capturar a las negras 8.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong><u><span class=\"has-inline-color has-vivid-cyan-blue-color\">PIEZAS AISLADAS<\/span><\/u><\/strong><\/strong> <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Una pieza que no tiene ninguna pieza a su lado es libre de mover cualquier n\u00famero de casillas en cualquier direcci\u00f3n, siempre que:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>no haga una captura, y<\/li><li>caiga junto al menos dos piezas (que pueden pertenecer a uno o a ambos jugadores).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong><u><span class=\"has-inline-color has-vivid-cyan-blue-color\">VENCEDOR<\/span><\/u><\/strong><\/strong> <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Un jugador gana capturando cinco piezas con las que pueda hacer una secuencia num\u00e9rica, como por ejemplo 3-4-5-6-7. (El orden en el que se hayan realizado las capturas no es importante). Un jugador tambi\u00e9n vence si el adversario no puede realizar ning\u00fan movimiento legal durante su turno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong><u><span class=\"has-inline-color has-vivid-cyan-blue-color\">VARIANTES<\/span><\/u><\/strong><\/strong> <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Para cambiar el ritmo y el tono, Campos de Acci\u00f3n pueden jugarse con otras configuraciones de apertura. Se recomienda que las piezas ocupen el mismo conjunto de casillas iniciales y que solo se reordenen los n\u00fameros; pero los jugadores pueden encontrar otras configuraciones que funcionen bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong><u><span class=\"has-inline-color has-vivid-cyan-blue-color\">HISTORIA<\/span><\/u><\/strong><\/strong> <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">En su libro de 1969 <a href=\"https:\/\/en.wikipedia.org\/wiki\/A_Gamut_of_Games\" target=\"_blank\" rel=\"noreferrer noopener\">A Gamut of Games<\/a>, Sid Sackson describi\u00f3 el juego de estrategia abstracto Lines of Action (LOA) dise\u00f1ado por Claude Soucie. (En Espa\u00f1a <a rel=\"noreferrer noopener\" href=\"https:\/\/labsk.net\/wkr\/archives\/809\/\" data-type=\"post\" data-id=\"809\" target=\"_blank\">Un mont\u00f3n de juegos<\/a> lo public\u00f3 RBA en 2007). A principios de la d\u00e9cada de 1980, LOA y una variante de Sackson titulada <a href=\"https:\/\/en.wikipedia.org\/wiki\/Fields_of_Action\" target=\"_blank\" rel=\"noreferrer noopener\">Fields of Action<\/a> aparecieron en la revista de juegos alemana <a href=\"https:\/\/spielbox.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Spielbox<\/a>. Una versi\u00f3n en ingl\u00e9s de Fields of Action se public\u00f3 en la edici\u00f3n de febrero-marzo de 1989 de GAMES Magazine.<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\"><em>Estas reglas son una traducci\u00f3n libre de Jos\u00e9 Carlos de Diego (WKR) de aquellas que aparecieron en la revista GAMES.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FICHA EN BGG:<\/strong><br><a href=\"https:\/\/boardgamegeek.com\/image\/1271142\/fields-action\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/boardgamegeek.com\/image\/1271142\/fields-action<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FICHA EN LA WIKIPEDIA:<\/strong><br><a rel=\"noreferrer noopener\" href=\"https:\/\/en.wikipedia.org\/wiki\/Fields_of_Action\" target=\"_blank\">https:\/\/en.wikipedia.org\/wiki\/Fields_of_Action<\/a><br><br><strong>ZILLIONS OF GAMES:<\/strong><br><a href=\"https:\/\/www.zillionsofgames.com\/cgi-bin\/zilligames\/submissions.cgi?do=show;id=409\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.zillionsofgames.com\/cgi-bin\/zilligames\/submissions.cgi?do=show;id=409<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un juego de estrategia para dos jugadores de Sid Sackson. MATERIALES Un tablero de ajedrez y dos juegos de damas de 12 piezas cada uno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20706,"comment_status":"open","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[979,2111,1041],"class_list":["post-20704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos-de-mesa","tag-abstracto","tag-fields-of-action","tag-sid-sackson"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/20704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=20704"}],"version-history":[{"count":4,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/20704\/revisions"}],"predecessor-version":[{"id":20710,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/20704\/revisions\/20710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/20706"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=20704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=20704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=20704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}