{"id":21194,"date":"2023-01-02T11:36:10","date_gmt":"2023-01-02T10:36:10","guid":{"rendered":"https:\/\/labsk.net\/wkr\/?p=21194"},"modified":"2023-01-05T15:58:18","modified_gmt":"2023-01-05T14:58:18","slug":"the-c64-mini","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/21194\/","title":{"rendered":"The C64 Mini"},"content":{"rendered":"\n<p class=\"justify-text wp-block-paragraph\">Mi regalo de estas Navidades ha sido <a rel=\"noreferrer noopener\" href=\"https:\/\/retrogames.biz\/products\/thec64-mini\/\" data-type=\"URL\" data-id=\"https:\/\/retrogames.biz\/products\/thec64-mini\/\" target=\"_blank\">The C64 Mini de RetroGames<\/a>. Es un buen cacharro para rememorar los viejos juegos del Commodore 64 (que en 2022 cumpli\u00f3 40 a\u00f1os). En esta entrada os voy a proporcionar toda la informaci\u00f3n que necesit\u00e1is para ponerlo a punto. Lleva algo de tiempo pero lo dejar\u00e9is todo fet\u00e9n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Manual de usuario<\/strong><\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Antes de hacer nada m\u00e9tele un repaso al <a rel=\"noreferrer noopener\" href=\"https:\/\/retrogames.biz\/support\/thec64-mini\/manuals\/\" target=\"_blank\">manual de usuario<\/a>. No hace falta que te lo estudies, pero al menos para que te suenen las cosas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Actualizar Firmware<\/strong><\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Lo primero que hay que hacer, s\u00ed o s\u00ed, es <a rel=\"noreferrer noopener\" href=\"https:\/\/retrogames.biz\/support\/thec64-mini\/upgrade\/\" target=\"_blank\">actualizar el firmware<\/a> que viene de f\u00e1brica. No os asust\u00e9is es tan f\u00e1cil como poner un fichero en un pendrive formateado en FAT32 y seguir las instrucciones. El \u00faltimo que hay hasta la fecha es el 1.6.1. Descomprime el bin en el ra\u00edz del pendrive y en el carrusel desde Device settings (icono de llave inglesa) &gt; System information. No tarda mucho, pero ten paciencia. Cuando termina se reinicia solo. Comprueba que la versi\u00f3n est\u00e1 actualizada. Lleva bastantes mejoras y una vez hecho tendr\u00e1s acceso al pendrive para cargar tus propias roms, lo que en la pr\u00e1ctica se traduce en miles de juegos a tu alcance (y no los 64 que viene de f\u00e1brica).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Backup de la NAND y los 64 juegos preinstalados<\/strong><\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Una vez actualizado (o antes de actualizar si lo prefieres) puedes hacer un backup de la NAND y el carrusel de juegos con la herramienta <a rel=\"noreferrer noopener\" href=\"https:\/\/megastyle.itch.io\/thec64-game-tool\" target=\"_blank\">TheC64GameTool<\/a>.  Ejecuta el exe bajo windows y elije Make FW. Marca \u00abBackup Games\u201d y \u201cBackup Nand\u201d y deja sin marcar la opci\u00f3n \u201cDelete all game first\u201d (esto es importante o borrar\u00e1s todo). Este proceso crear\u00e1 un binario TheC6409_9_9.bin que debemos colocar en el ra\u00edz del pendrive. <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Si hacemos una actualizaci\u00f3n de firmware de nuevo, en este caso lo que har\u00e1 es crear unos ficheros \u201cgames_backup_YYYY.MM.DD-HH.MM_01.tar\u201d, \u201cnanda_backup_YYYY.MM.DD-HH.MM_01.bin\u201d y \u201cnandb_backup_YYYY.MM.DD-HH.MM_01.bin\u201d en la ra\u00edz del pendrive. Estos tres ficheros son el backup completo. Gu\u00e1rdalos a buen recaudo. Esto lo descubr\u00ed gracias a Commodore Spain en <a rel=\"noreferrer noopener\" href=\"https:\/\/www.commodorespain.es\/como-anadir-juegos-al-carrusel-del-the-c64-maxi-y-mini\/\" target=\"_blank\">este hilo<\/a>. <\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\"><strong>IMPORTANTE<\/strong>: El backup games_backup solo es del idioma ingl\u00e9s, por lo tanto si lo vuelves a recuperar y pones el idioma espa\u00f1ol en la consola perder\u00e1s la descripci\u00f3n de los juegos en el carrusel. Tenlo en cuenta (en el tar est\u00e1n todos los ficheros de configuraci\u00f3n de cada juego con los textos en espa\u00f1ol).<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Se puede acceder de otra manera a la nand de la consola pero toca <a href=\"https:\/\/thec64community.online\/thread\/76\/thec64-modding-games-little-guide\" target=\"_blank\" rel=\"noreferrer noopener\">hacerse un cable UART serial y destripar la consola<\/a>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A\u00f1adir juegos al Carrusel<\/strong><\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Este m\u00e9todo est\u00e1 obsoleto, ahora se usa <strong>Project Carousel USB Anniversary Edition<\/strong>. Una vez tienes un backup de todo puedes a\u00f1adir tus propios juegos al carrusel (hasta 150) creando un FW personalizado. En el <a rel=\"noreferrer noopener\" href=\"https:\/\/www.commodorespain.es\/como-anadir-juegos-al-carrusel-del-the-c64-maxi-y-mini\/\" target=\"_blank\">mismo hilo<\/a> de Commodore Spain te explica c\u00f3mo hacerlo. Lo \u00fanico es que al usar el backup que hicimos anteriormente perder\u00e1s la descripci\u00f3n de los juegos en espa\u00f1ol. O pones la consola en ingl\u00e9s o te tocar\u00e1 escribirlos uno a uno. Tenlo en cuenta. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Project Carousel USB Anniversary Edition<\/strong><\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">El nuevo m\u00e9todo para gestionar carruseles en The C64 Mini. Hoy por hoy, es lo que se recomienda. Lo que hace es crear un FW falso que se lanza igual que para actualizar la consola, pero en lugar de actualizarla lo que hace es lanzar su propio FW modificado temporal. Este m\u00e9todo es seguro ya que no modifica la consola, siempre y cuando no a\u00f1adas el autoboot ni sobreescribas nada. Todo se hace desde el pendrive. Cada vez que quieras arrancar tus carruseles tendr\u00e1s que lanzar de nuevo el FW modificado temporal. En el C64 Mini las teclas son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cambiar versi\u00f3n de carrusel de otro FW: Men\u00fa + bot\u00f3n tri\u00e1ngulo izquierdo.<\/li>\n\n\n\n<li>Cambiar de modo (tema Amiga, Atari, Linux, Retroarch y VICE): Menu + bot\u00f3n tri\u00e1ngulo derecho.<\/li>\n\n\n\n<li>Cambiar a un carrusel de juegos diferente: Men\u00fa + bot\u00f3n Disparo izquierdo 1<\/li>\n\n\n\n<li>Men\u00fa de opciones de PCUAE (ojo con esto que si no sabes lo que haces la puedes liar): bot\u00f3n Disparo derecho 2<\/li>\n<\/ul>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Para crear tus propios carruseles tienes que usar <a rel=\"noreferrer noopener\" href=\"https:\/\/thec64community.online\/thread\/603\/pcuae-manager\" target=\"_blank\">PCUAE Manager<\/a>. La gente de Commodore Spain tiene <a rel=\"noreferrer noopener\" href=\"https:\/\/youtu.be\/HPL6fJP-IkE?list=PLlFU1hF8N0RoYbQdsBZy7EINpMy8nouDY\" target=\"_blank\">un v\u00eddeo en youtube que lo explica bastante bien<\/a> (y en la descripci\u00f3n tienes una distro ya montada con juegos \u00abmade in spain\u00bb). Cualquier informaci\u00f3n o si deseas hablar sobre PCUAE, acude al <a rel=\"noreferrer noopener\" href=\"https:\/\/thec64community.online\" target=\"_blank\">Foro de la comunidad THEC64<\/a>. El manual de PCUAE est\u00e1 aqu\u00ed:&nbsp;<a href=\"https:\/\/github.com\/CommodoreOS\/PCUAE\/wiki\">https:\/\/github.com\/CommodoreOS\/PCUAE\/wiki<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Configurando los ficheros CJM<\/strong><\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Puedes organizar el pendrive en carpetas de la manera que mejor te convenga. Puedes navegar y cargar estas roms desde el icono de pendrive, pero para que el TheC64 Mini te reconozca las teclas de los juegos con el joystick y no tengas que andar con el teclado virtual (perdiendo un considerable tiempo) hay que configurar unos ficheros con extensi\u00f3n CJM con el mismo nombre del juego. Por suerte hay una herramienta llamada <a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/drive\/folders\/1G58teTaXt-6WuYjYW-5qAm67sJEFxA-9\" target=\"_blank\">c64MiniLoaderCFG<\/a> que nos facilitar\u00e1 bastante el proceso. Si eres masoca, en el manual de usuario hay un anexo que te explica c\u00f3mo hacerlo editando ficheros de texto a mano. Si quieres ver algunos ejemplos, en este hilo de <a rel=\"noreferrer noopener\" href=\"https:\/\/thec64community.online\/thread\/228\/definitive-game-collection-loader-version\" target=\"_blank\">thec64community<\/a> tienes una buena recopilaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Configurar otros mandos<\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Es una pesadilla. Los botones no est\u00e1n mapeados correctamente, a pesar de que aseguran que han a\u00f1adido en los \u00faltimos firmwares la configuraci\u00f3n de unos cuantos. Yo prob\u00e9 varios y el \u00fanico que me reconoc\u00eda era una GamePad de GameWare cutr\u00f3n (con dos sticks). Una pista de algunos mappers:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"253\" src=\"https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2023\/01\/TheC64-Joystick-Matrix-c1-1024x253.png\" alt=\"\" class=\"wp-image-21213\" srcset=\"https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2023\/01\/TheC64-Joystick-Matrix-c1-1024x253.png 1024w, https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2023\/01\/TheC64-Joystick-Matrix-c1-300x74.png 300w, https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2023\/01\/TheC64-Joystick-Matrix-c1-768x190.png 768w, https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2023\/01\/TheC64-Joystick-Matrix-c1-1536x380.png 1536w, https:\/\/labsk.net\/wkr\/wp-content\/uploads\/2023\/01\/TheC64-Joystick-Matrix-c1.png 1605w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En mi caso la cosa qued\u00f3 as\u00ed con el Puerto #2 por defecto:<br>X:pal,driveicon<br>J:1:JU,JD,JL,JR,JF,JF,SP,CM,CM,SL,SR,RS,SP<br>J:2*:JU,JD,JL,JR,RS,CM,JF,H,EN,SP,L,RE,HM<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Con peque\u00f1as variaciones, en donde est\u00e1 la H y la L. Pero al menos me funciona el D-PAD y el stick izquierdo, el bot\u00f3n de disparo y la barra espaciadora. Y he podido configurar algunos botones extras como el RUN\/STOP, C64, Return y Restore. Aun as\u00ed tengo que usar los gatillos izquierdos para algunas cosas. Todo es acostumbrarse.<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Desde el PCUAE Manager tambi\u00e9n se pueden configurar los CJM.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Joystick #1<\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Algunos juegos requieren que configures el joystick predeterminado del C64 para que se asigne al Puerto #1 del joystick del c64 original. De forma predeterminada, el joystick del C64 Mini se asigna al Puerto #2 del c64 original. Para hacerlo basta con:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Renombrar: mijuego.d64<br>Y cambiar el nombre a: mijuego_J1.d64  (a\u00f1adiendo un _J1 al final del nombre del juego).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Accurate Disk<\/h3>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Algunos juegos requieren que se use la configuraci\u00f3n de \u00abdisco preciso\u00bb para que funcionen correctamente. Sin embargo, esta configuraci\u00f3n reducir\u00e1 la velocidad del disco a las velocidades de carga originales del c64 (lentas):<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Renombrar: mijuego.d64<br>Y cambiar el nombre a: mijuego_AD.d64  (a\u00f1adiendo un _AD al final del nombre del juego).<\/p>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Hay algunos juegos extremadamente obstinados que a\u00fan no funcionar\u00e1n si simplemente usas el indicador &#8216;_AD&#8217;, pero&nbsp;<em>adem\u00e1s<\/em>&nbsp;, tambi\u00e9n debes asegurarte de iniciarlos desde el men\u00fa con la opci\u00f3n &#8216;fasterloader&#8217; desactivada:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>De donde bajar roms<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/csdb.dk\/search\/advanced.php\" target=\"_blank\">https:\/\/csdb.dk\/search\/advanced.php<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/csdb.dk\/latestreleases.php\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/csdb.dk\/latestreleases.php<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/c64g.com\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/c64g.com<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/computeremuzone.com\/c64\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/computeremuzone.com\/c64\/<\/a><\/li>\n\n\n\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/itch.io\/games\/tag-commodore-64\" target=\"_blank\">https:\/\/itch.io\/games\/tag-commodore-64<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.c64.com\/games\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.c64.com\/games<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.c64games.de\/phpseiten\/spiele.php\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.c64games.de\/phpseiten\/spiele.php<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.indieretronews.com\/search\/label\/C64\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.indieretronews.com\/search\/label\/C64<\/a><\/li>\n\n\n\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.planetemu.net\/roms\/commodore-c64-games-d64\" target=\"_blank\">https:\/\/www.planetemu.net\/roms\/commodore-c64-games-d64<\/a><\/li>\n\n\n\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.nightfallcrew.com\/tag\/c64-big-game-pack\/\" target=\"_blank\">https:\/\/www.nightfallcrew.com\/tag\/c64-big-game-pack\/<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/archive.org\/details\/commodore-64-romset-us\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/archive.org\/details\/commodore-64-romset-us<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/archive.org\/download\/C64RomCollectionByGhostware\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/archive.org\/download\/C64RomCollectionByGhostware<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/archive.org\/details\/softwarelibrary_c64\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/archive.org\/details\/softwarelibrary_c64<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>M\u00e1s info<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/retrogames.biz\/products\/thec64-mini\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/retrogames.biz\/products\/thec64-mini\/<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/thec64community.online\/board\/37\/thec64-games-files-loader-classic\">https:\/\/thec64community.online\/board\/37\/thec64-games-files-loader-classic<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"justify-text wp-block-paragraph\">Conforme vaya descubriendo cosas para este cacharro ir\u00e9 actualizando este hilo. D\u00e9jatelo preparado en marcadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi regalo de estas Navidades ha sido The C64 Mini de RetroGames. Es un buen cacharro para rememorar los viejos juegos del Commodore 64 (que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21195,"comment_status":"open","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[132,12],"tags":[2181],"class_list":["post-21194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software","category-videojuegos","tag-thec64mini"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/21194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=21194"}],"version-history":[{"count":18,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/21194\/revisions"}],"predecessor-version":[{"id":21226,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/21194\/revisions\/21226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/21195"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=21194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=21194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=21194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}