{"id":3750,"date":"2009-05-21T13:40:42","date_gmt":"2009-05-21T12:40:42","guid":{"rendered":"http:\/\/www.labsk.net\/wkr\/?p=3750"},"modified":"2009-05-21T13:47:43","modified_gmt":"2009-05-21T12:47:43","slug":"no-hay-salas-para-tanto-cine-espanol","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/3750\/","title":{"rendered":"No hay salas para tanto cine (espa\u00f1ol)"},"content":{"rendered":"<p>Un ilustrativo <a href=\"http:\/\/www.elpais.com\/articulo\/sociedad\/hay\/salas\/cine\/espanol\/elpepusoc\/20090521elpepisoc_1\/Tes\" target=\"_blank\">art\u00edculo aparecido en \u00abEl Pa\u00eds\u00bb<\/a> que pone de manifiesto el verdadero problema que arrastra el denominado cine espa\u00f1ol, y es sencillamente, que hacen pel\u00edculas que no interesan a nadie. Destacable el hecho de que en el a\u00f1o pasado se rodaron 173 filmes gracias a las ayudas oficiales, de las cuales 24 pel\u00edculas obtuvieron menos de 100 espectadores (no se si en este n\u00famero se excluyen a los familiares y amigos) y otras 46 a\u00fan no se hayan estrenado a d\u00eda de hoy.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ilustrativo art\u00edculo aparecido en \u00abEl Pa\u00eds\u00bb que pone de manifiesto el verdadero problema que arrastra el denominado cine espa\u00f1ol, y es sencillamente, que hacen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[7],"tags":[103],"class_list":["post-3750","post","type-post","status-publish","format-standard","hentry","category-miscelanea","tag-cine"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/3750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=3750"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/3750\/revisions"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=3750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=3750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=3750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}