{"id":5929,"date":"2010-01-15T11:53:58","date_gmt":"2010-01-15T10:53:58","guid":{"rendered":"http:\/\/www.labsk.net\/wkr\/?p=5929"},"modified":"2018-01-29T15:11:45","modified_gmt":"2018-01-29T14:11:45","slug":"los-seis-palos","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/5929\/","title":{"rendered":"Los Seis Palos"},"content":{"rendered":"<p style=\"text-align: justify;\">El <a href=\"http:\/\/decktet.wikidot.com\/\" target=\"_blank\" rel=\"noopener\">mazo de Decktet<\/a> es algo peculiar, al contrario que muchos otros juegos de cartas este contiene 6 palos diferentes, lo que hace que para generar nuestras aventuras ratoniles sea mucho m\u00e1s plural y haya una mayor variabilidad. Otra de las peculiaridades es que muchas de las cartas pertenecen a dos palos simult\u00e1neamente, con lo cual podemos hilar algo m\u00e1s fino nuestras aventuras.<\/p>\n<p style=\"text-align: justify;\">Las cartas hablan, comunican. Se requiere concentraci\u00f3n y dejar el escepticismo a un lado, aunque jam\u00e1s el sentido del humor, para entender que si bien es posible que el destino de la humanidad ratonil est\u00e9 escrito, tambi\u00e9n lo es que las faltas de ortograf\u00eda impidan. Cada carta representa una parcela en la vida, cada palo de Decket (recuerda que son seis) simboliza las diferentes fuerzas espirituales y elementos materiales impulsores de las vivencias del cosmos. As\u00ed que cada carta, en mayor o menor medida, se ha de saber interpretar. La lectura, pues, debe hacerse desde la prudencia y el optimismo de que siempre que se cierra una puerta se abre una ventana. Jam\u00e1s se ha de perder el sentido de la orientaci\u00f3n, cada cosa tiene su sitio, s\u00f3lo que en ocasiones, no es el que pensamos.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-19830 aligncenter\" src=\"http:\/\/labsk.net\/wkr\/wp-content\/uploads\/2018\/01\/suits-all.gif\" alt=\"\" width=\"391\" height=\"185\" \/><\/p>\n<p style=\"text-align: justify;\">El <strong>significado de los seis palos<\/strong> es el siguiente:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Lunas.<\/strong> Representa la sabidur\u00eda, la sabidur\u00eda divina, en especial. Se asocia con los misterios, lo oculto, y la verdad ineludible de que el mundo supera a nuestro conocimiento. Si tienes una trama argumental principal en tu campa\u00f1a la luna har\u00e1 referencia a ella.<\/li>\n<li style=\"text-align: justify;\"><strong>Soles<\/strong>. Representa el poder, tal vez el poder divino. Se asocia con una acci\u00f3n decisiva y un prop\u00f3sito claro. La Comunidad. Hace referencia a los Ratones.<\/li>\n<li style=\"text-align: justify;\"><strong>Olas de agua<\/strong>. Es la mano de la tierra, que ejerce presi\u00f3n sobre todas las cosas. Representa la naturaleza como una fuerza activa. Se asocia con el clima, los ciclos naturales, y el paso del tiempo. Hace referencia al Clima.<\/li>\n<li style=\"text-align: justify;\"><strong>Madera.<\/strong> La madera es el regalo de la tierra, de la que las cosas empiezan y en el que las cosas terminan. Representa la naturaleza como materia. Tambi\u00e9n conocida como las hojas o los \u00e1rboles, este palo est\u00e1 relacionado con las materias primas y productos alimenticios. Hace referencia a la Naturaleza Salvaje (Wilderness).<\/li>\n<li style=\"text-align: justify;\"><strong>Wyvernas.<\/strong> Lo antinatural, mal\u00e9fico y lo underground, el Wyrm trae la violencia y se alimenta de sue\u00f1os. Este es palo m\u00e1s negativo. M\u00e1s ampliamente, representa lo que es inapropiado o perjudicial. El Depredador. Hace referencia a los Animales.<\/li>\n<li style=\"text-align: justify;\"><strong>Nudos.<\/strong> Representa oficio, habilidad y refinamiento. Se asocia con los productos manufacturados, el comercio y el dinero. Recursos y Contactos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El mazo de Decktet es algo peculiar, al contrario que muchos otros juegos de cartas este contiene 6 palos diferentes, lo que hace que para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[4,8],"tags":[460,133,463,283,471],"class_list":["post-5929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos-de-rol","category-proyectos","tag-ayuda-de-juego","tag-decktet","tag-generador","tag-mouse-guard","tag-palos"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/5929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=5929"}],"version-history":[{"count":2,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/5929\/revisions"}],"predecessor-version":[{"id":19833,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/5929\/revisions\/19833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media\/18502"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=5929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=5929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=5929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}