{"id":6361,"date":"2010-03-19T08:56:43","date_gmt":"2010-03-19T07:56:43","guid":{"rendered":"http:\/\/www.labsk.net\/wkr\/?p=6361"},"modified":"2012-02-10T09:36:40","modified_gmt":"2012-02-10T08:36:40","slug":"heraldo-de-aragon-y-los-print-and-play","status":"publish","type":"post","link":"https:\/\/labsk.net\/wkr\/archives\/6361\/","title":{"rendered":"Heraldo de Arag\u00f3n y los Print &#038; Play"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/i624.photobucket.com\/albums\/tt323\/diariowkr\/_imagen_games_copia_62d237b8.jpg\" alt=\"Print-and-play Heraldo de Arag\u00f3n\" width=\"600\" \/><\/p>\n<p style=\"text-align: justify;\">Ya avis\u00e9 en su d\u00eda, que <a href=\"http:\/\/www.labsk.net\/wkr\/archives\/6275\" target=\"_blank\">mi entrevista en el \u00abHeraldo de Arag\u00f3n\u00bb<\/a>, solo era el principio. Quedaba pendiente otra cosa que estaba coci\u00e9ndose en la redacci\u00f3n del peri\u00f3dico, y del que no pod\u00eda dar muchos detalles. Pues bien, esto que ahora anuncio es la continuaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Se ha conseguido <a href=\"http:\/\/www.heraldo.es\/noticias\/sociedad\/print_play.html\" target=\"_blank\"><strong>un hito<\/strong><\/a> (un acontecimiento que va a servir de punto de referencia) en Espa\u00f1a acerca de los juegos de mesa. Si no me equivoco es la primera vez que un peri\u00f3dico, en este caso \u00abHeraldo de Arag\u00f3n\u00bb (ten\u00eda que ser en Zaragoza), dedica <strong><a href=\"http:\/\/www.heraldo.es\/noticias\/sociedad\/print_play.html\" target=\"_blank\">parte de su espacio cultural<\/a> en MVT (a doble p\u00e1gina) a los juegos<\/strong> <a href=\"http:\/\/www.labsk.net\/wkr\/archives\/tag\/print-and-play\" target=\"_blank\"><strong>print-and-play<\/strong><\/a> (de los que soy ac\u00e9rrimo defensor) y a <strong>tres de los m\u00e1s prol\u00edficos creadores de juegos en Espa\u00f1a<\/strong>. Tambi\u00e9n aparece anunciado el art\u00edculo en portada del peri\u00f3dico.<\/p>\n<p style=\"text-align: justify;\">Hoy somos protagonistas, por nuestros juegos, <strong>Perepau Llistosella<\/strong> (de <a href=\"http:\/\/kokorin.wordpress.com\/\" target=\"_blank\">\u00ab<\/a><a href=\"http:\/\/kokorin.wordpress.com\/\" target=\"_blank\">Kok\u00f6r\u00een  Kolorado<\/a><a href=\"http:\/\/kokorin.wordpress.com\/\" target=\"_blank\">\u00ab<\/a>), <strong>Alberto Corral<\/strong> (de <a href=\"http:\/\/mundosdecarton.blogspot.com\" target=\"_blank\">\u00abMundos de Cart\u00f3n\u00bb<\/a>) y yo mismo, <strong>Jos\u00e9 Carlos de Diego<\/strong> (de <a href=\"http:\/\/blog.labsk.net\">\u00abDiario de WKR\u00bb<\/a>). Por si no fuera poco, adem\u00e1s, cada uno hemos cedido 3 de nuestros juegos print-and-play (<a href=\"http:\/\/www.heraldo.es\/index.php\/mod.enlaces\/mem.detalle\/idenlace.1023\/cat.105\" target=\"_blank\">Formula 3000<\/a>, <a href=\"http:\/\/www.heraldo.es\/index.php\/mod.enlaces\/mem.detalle\/idenlace.1024\/cat.105\" target=\"_blank\">24: Juego de Reyes<\/a> y <a href=\"http:\/\/www.heraldo.es\/index.php\/mod.enlaces\/mem.detalle\/idenlace.1026\/cat.105\" target=\"_blank\">Froggy Land<\/a>, respectivamente) para que los lectores del peri\u00f3dico puedan <strong>descarg\u00e1rselos, imprim\u00edrselos, jugarlos y dejar sus opiniones en la p\u00e1gina online del peri\u00f3dico<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Toda una declaraci\u00f3n de intenciones. Por primera vez en mucho tiempo que en un peri\u00f3dico se habla de juegos de mesa print-and-play en la secci\u00f3n de cultura, se juega y se trata como lo que son: <strong>ocio cultural<\/strong>. Y estoy feliz porque yo he tenido \u00abalgo\u00bb que ver con ello.<\/p>\n<p style=\"text-align: justify;\"><strong>Edito.<\/strong> Probablemente la primera vez que se habl\u00f3 en Espa\u00f1a de juegos de mesa en un peri\u00f3dico fue all\u00e1 por 1982 de la mano de <a href=\"http:\/\/www.comascoma.com\/\" target=\"_blank\">Oriol Comas<\/a> en \u00abEl Pa\u00eds\u00bb y antes ya hab\u00eda escrito en el \u00abAvui\u00bb de Barcelona.<\/p>\n<p style=\"text-align: justify;\"><strong>Edito.<\/strong> La noticia e\u00a0 im\u00e1genes en <a href=\"http:\/\/kokorin.wordpress.com\/2010\/03\/19\/heraldo-de-aragon-pp-de-mariano-garcia\/\" target=\"_blank\">Kok\u00f6r\u00een Kolorado<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya avis\u00e9 en su d\u00eda, que mi entrevista en el \u00abHeraldo de Arag\u00f3n\u00bb, solo era el principio. Quedaba pendiente otra cosa que estaba coci\u00e9ndose en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[135,210,507,48],"class_list":["post-6361","post","type-post","status-publish","format-standard","hentry","category-juegos-de-mesa","tag-entrevista","tag-froggy-land","tag-heraldo-de-aragon","tag-print-and-play"],"_links":{"self":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/6361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/comments?post=6361"}],"version-history":[{"count":0,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/posts\/6361\/revisions"}],"wp:attachment":[{"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/media?parent=6361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/categories?post=6361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labsk.net\/wkr\/wp-json\/wp\/v2\/tags?post=6361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}